{"id":21500,"date":"2024-03-14T20:01:36","date_gmt":"2024-03-14T19:01:36","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/?post_type=coopsudoe&#038;p=21500"},"modified":"2024-03-14T20:01:36","modified_gmt":"2024-03-14T19:01:36","slug":"coceder","status":"publish","type":"coopsudoe","link":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/","title":{"rendered":"COCEDER"},"content":{"rendered":"<p>Somos una confederaci\u00f3n de centros de desarrollo rural y nuestro prop\u00f3sito es Que el desarrollo de la vida en el medio rural sea social y ambientalmente sostenible, posibilitando que la poblaci\u00f3n realice su proyecto vital en igualdad de oportunidades. Nuestro principal objetivo es el desarrollo social, evitando que el colectivo de personas que viven en el medio rural quede excluido de unos niveles suficientes de bienestar, as\u00ed como la lucha por la inclusi\u00f3n social, la coherencia y los derechos sociales. Trabajamos con todos los grupos de poblaci\u00f3n en el medio rural con diferentes programas estatales, auton\u00f3micos y europeos<\/p>\n","protected":false},"featured_media":21499,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"area-de-competencia":[1969,1985,1998,1994,1999,1991,2003,2000,2007,1997,2004,1982,2008],"beneficiario-implicado":[],"coopsudoe-tipo":[1931],"entidades":[2058,1967],"idioma":[2011],"interesado":[1957,1956],"objetivo-especifico":[1952,1949,1951,2115,2114],"paises":[51],"perfil":[],"sector-coop":[],"class_list":["post-21500","coopsudoe","type-coopsudoe","status-publish","has-post-thumbnail","hentry","area-de-competencia-adaptacion-al-cambio-climatico","area-de-competencia-cohesion-social-y-equlibrio-territorial","area-de-competencia-creacion-de-empleo","area-de-competencia-economia-circular","area-de-competencia-economia-social-y-empresas-sociales","area-de-competencia-emprendimiento","area-de-competencia-envejecimiento-activo","area-de-competencia-igualdad-de-oportunidades-y-la-participacion-activa-en-la-sociedad","area-de-competencia-inclusion-e-innovacion-social","area-de-competencia-innovacion-social-la-valorizacion-del-patrimonio-y-los-servicios","area-de-competencia-prestacion-de-servicios-asistenciales-locales-y-familiares","area-de-competencia-proteccion-de-la-naturaleza-y-la-biodversidad-patrimonio-y-recusos-naturales-infraestructuras-verdes-y-azules","area-de-competencia-proteccion-desarrollo-y-promocion-del-patrimonio-cultural-y-los-servicios-culturales","coopsudoe-tipo-organizacion","entidades-grupos-de-interes-incluidas-ongs","entidades-organizacion","idioma-espanol","interesado-formar-parte-de-un-proyecto","interesado-liderar-un-proyecto","objetivo-especifico-os-1-1-desarrollar-y-mejorar-las-capacidades-de-investigacion-e-innovacion-y-asimilar-tecnologias-avanzadas","objetivo-especifico-os-2-4-favorecer-la-adaptacion-al-cambio-climatico-y-la-prevencion-del-riesgo-de-catastrofes-asi-como-la-resiliencia-teniendo-en-cuenta-los-enfoques-basados-en-los-ecosistemas","objetivo-especifico-os-2-7-incrementar-la-proteccion-y-la-conservacion-de-la-naturaleza-la-biodiversidad-y-las-infraestructuras-verdes-tambien-en-las-zonas-urbanas-y-reducir-toda-forma-de-contaminacion","objetivo-especifico-os-4-1","objetivo-especifico-os-4-5","paises-espana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COCEDER - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COCEDER - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"Somos una confederaci\u00f3n de centros de desarrollo rural y nuestro prop\u00f3sito es Que el desarrollo de la vida en el medio rural sea social y ambientalmente sostenible, posibilitando que la poblaci\u00f3n realice su proyecto vital en igualdad de oportunidades. Nuestro principal objetivo es el desarrollo social, evitando que el colectivo de personas que viven en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/jet-form-builder\/8ff2cbe1d445cb32549c465066e8fec5\/2024\/03\/COCEDER-LOGO_CMYK-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1980\" \/>\n\t<meta property=\"og:image:height\" content=\"1546\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/coceder\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/coceder\\\/\",\"name\":\"COCEDER - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/coceder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/coceder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/jet-form-builder\\\/8ff2cbe1d445cb32549c465066e8fec5\\\/2024\\\/03\\\/COCEDER-LOGO_CMYK-scaled.jpg\",\"datePublished\":\"2024-03-14T19:01:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/coceder\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/coceder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/coceder\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/jet-form-builder\\\/8ff2cbe1d445cb32549c465066e8fec5\\\/2024\\\/03\\\/COCEDER-LOGO_CMYK-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/jet-form-builder\\\/8ff2cbe1d445cb32549c465066e8fec5\\\/2024\\\/03\\\/COCEDER-LOGO_CMYK-scaled.jpg\",\"width\":1980,\"height\":1546},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/coceder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COCEDER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COCEDER - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/","og_locale":"fr_FR","og_type":"article","og_title":"COCEDER - Interreg Sudoe","og_description":"Somos una confederaci\u00f3n de centros de desarrollo rural y nuestro prop\u00f3sito es Que el desarrollo de la vida en el medio rural sea social y ambientalmente sostenible, posibilitando que la poblaci\u00f3n realice su proyecto vital en igualdad de oportunidades. Nuestro principal objetivo es el desarrollo social, evitando que el colectivo de personas que viven en [&hellip;]","og_url":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","og_image":[{"width":1980,"height":1546,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/jet-form-builder\/8ff2cbe1d445cb32549c465066e8fec5\/2024\/03\/COCEDER-LOGO_CMYK-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/","url":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/","name":"COCEDER - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/#primaryimage"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/#primaryimage"},"thumbnailUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/jet-form-builder\/8ff2cbe1d445cb32549c465066e8fec5\/2024\/03\/COCEDER-LOGO_CMYK-scaled.jpg","datePublished":"2024-03-14T19:01:36+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/#primaryimage","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/jet-form-builder\/8ff2cbe1d445cb32549c465066e8fec5\/2024\/03\/COCEDER-LOGO_CMYK-scaled.jpg","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/jet-form-builder\/8ff2cbe1d445cb32549c465066e8fec5\/2024\/03\/COCEDER-LOGO_CMYK-scaled.jpg","width":1980,"height":1546},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/coceder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"COCEDER"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/fr\/#website","url":"https:\/\/interreg-sudoe.eu\/fr\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/coopsudoe\/21500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/coopsudoe"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/types\/coopsudoe"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media\/21499"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media?parent=21500"}],"wp:term":[{"taxonomy":"area-de-competencia","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/area-de-competencia?post=21500"},{"taxonomy":"beneficiario-implicado","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/beneficiario-implicado?post=21500"},{"taxonomy":"coopsudoe-tipo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/coopsudoe-tipo?post=21500"},{"taxonomy":"entidades","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/entidades?post=21500"},{"taxonomy":"idioma","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/idioma?post=21500"},{"taxonomy":"interesado","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/interesado?post=21500"},{"taxonomy":"objetivo-especifico","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/objetivo-especifico?post=21500"},{"taxonomy":"paises","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/paises?post=21500"},{"taxonomy":"perfil","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/perfil?post=21500"},{"taxonomy":"sector-coop","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/sector-coop?post=21500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}