{"id":23017,"date":"2024-03-22T17:44:55","date_gmt":"2024-03-22T16:44:55","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/?post_type=coopsudoe&#038;p=23017"},"modified":"2024-03-22T17:44:55","modified_gmt":"2024-03-22T16:44:55","slug":"diego-gonzalez-torralba","status":"publish","type":"coopsudoe","link":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/","title":{"rendered":"Diego Gonz\u00e1lez Torralba"},"content":{"rendered":"<p>Actualmente estamos liderando 2 proyectos LIFE, estamos como socios en 2 Interreg y estamos en proceso de resolucion de varios proyectos m\u00e1s<\/p>\n","protected":false},"featured_media":23016,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"area-de-competencia":[1969,1994,1975,1970,1980,1979,1973],"beneficiario-implicado":[],"coopsudoe-tipo":[1930],"entidades":[1959],"idioma":[2011,2913],"interesado":[1957],"objetivo-especifico":[1949,1951,1954],"paises":[51],"perfil":[],"sector-coop":[],"class_list":["post-23017","coopsudoe","type-coopsudoe","status-publish","has-post-thumbnail","hentry","area-de-competencia-adaptacion-al-cambio-climatico","area-de-competencia-economia-circular","area-de-competencia-gestion-hidrica","area-de-competencia-prevencion-de-inundaciones","area-de-competencia-rehabilitacion-de-zonas-industrailes-y-terrenos-contaminados","area-de-competencia-reutilizacion-de-materiales-reduccion-y-valorizacion-de-residuos","area-de-competencia-sequias","coopsudoe-tipo-miembro","entidades-autoridad-publica-regional","idioma-espanol","idioma-ingles","interesado-formar-parte-de-un-proyecto","objetivo-especifico-os-2-4-favorecer-la-adaptacion-al-cambio-climatico-y-la-prevencion-del-riesgo-de-catastrofes-asi-como-la-resiliencia-teniendo-en-cuenta-los-enfoques-basados-en-los-ecosistemas","objetivo-especifico-os-2-7-incrementar-la-proteccion-y-la-conservacion-de-la-naturaleza-la-biodiversidad-y-las-infraestructuras-verdes-tambien-en-las-zonas-urbanas-y-reducir-toda-forma-de-contaminacion","objetivo-especifico-os-4-6-potenciar-el-papel-de-la-cultura-y-el-turismo-sostenible-en-el-desarrollo-economico-la-inclusion-social-y-la-innovacion-social","paises-espana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diego Gonz\u00e1lez Torralba - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diego Gonz\u00e1lez Torralba - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"Actualmente estamos liderando 2 proyectos LIFE, estamos como socios en 2 Interreg y estamos en proceso de resolucion de varios proyectos m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/jet-form-builder\/f4076308d669281fc94d22c4d51e0ee3\/2024\/03\/Foto-DGT-Ene.-2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/diego-gonzalez-torralba\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/diego-gonzalez-torralba\\\/\",\"name\":\"Diego Gonz\u00e1lez Torralba - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/diego-gonzalez-torralba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/diego-gonzalez-torralba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/jet-form-builder\\\/f4076308d669281fc94d22c4d51e0ee3\\\/2024\\\/03\\\/Foto-DGT-Ene.-2024.jpg\",\"datePublished\":\"2024-03-22T16:44:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/diego-gonzalez-torralba\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/diego-gonzalez-torralba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/diego-gonzalez-torralba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/jet-form-builder\\\/f4076308d669281fc94d22c4d51e0ee3\\\/2024\\\/03\\\/Foto-DGT-Ene.-2024.jpg\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/jet-form-builder\\\/f4076308d669281fc94d22c4d51e0ee3\\\/2024\\\/03\\\/Foto-DGT-Ene.-2024.jpg\",\"width\":768,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/diego-gonzalez-torralba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diego Gonz\u00e1lez Torralba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diego Gonz\u00e1lez Torralba - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/","og_locale":"fr_FR","og_type":"article","og_title":"Diego Gonz\u00e1lez Torralba - Interreg Sudoe","og_description":"Actualmente estamos liderando 2 proyectos LIFE, estamos como socios en 2 Interreg y estamos en proceso de resolucion de varios proyectos m\u00e1s","og_url":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","og_image":[{"width":768,"height":1024,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/jet-form-builder\/f4076308d669281fc94d22c4d51e0ee3\/2024\/03\/Foto-DGT-Ene.-2024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/","url":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/","name":"Diego Gonz\u00e1lez Torralba - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/#primaryimage"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/#primaryimage"},"thumbnailUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/jet-form-builder\/f4076308d669281fc94d22c4d51e0ee3\/2024\/03\/Foto-DGT-Ene.-2024.jpg","datePublished":"2024-03-22T16:44:55+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/#primaryimage","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/jet-form-builder\/f4076308d669281fc94d22c4d51e0ee3\/2024\/03\/Foto-DGT-Ene.-2024.jpg","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/jet-form-builder\/f4076308d669281fc94d22c4d51e0ee3\/2024\/03\/Foto-DGT-Ene.-2024.jpg","width":768,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/diego-gonzalez-torralba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Diego Gonz\u00e1lez Torralba"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/fr\/#website","url":"https:\/\/interreg-sudoe.eu\/fr\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/coopsudoe\/23017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/coopsudoe"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/types\/coopsudoe"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media\/23016"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media?parent=23017"}],"wp:term":[{"taxonomy":"area-de-competencia","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/area-de-competencia?post=23017"},{"taxonomy":"beneficiario-implicado","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/beneficiario-implicado?post=23017"},{"taxonomy":"coopsudoe-tipo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/coopsudoe-tipo?post=23017"},{"taxonomy":"entidades","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/entidades?post=23017"},{"taxonomy":"idioma","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/idioma?post=23017"},{"taxonomy":"interesado","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/interesado?post=23017"},{"taxonomy":"objetivo-especifico","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/objetivo-especifico?post=23017"},{"taxonomy":"paises","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/paises?post=23017"},{"taxonomy":"perfil","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/perfil?post=23017"},{"taxonomy":"sector-coop","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/sector-coop?post=23017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}