{"id":33361,"date":"2024-05-16T11:51:14","date_gmt":"2024-05-16T09:51:14","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/?post_type=coopsudoe&#038;p=33361"},"modified":"2024-05-16T11:51:14","modified_gmt":"2024-05-16T09:51:14","slug":"aurelio-garcia","status":"publish","type":"coopsudoe","link":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/aurelio-garcia\/","title":{"rendered":"Aurelio Garc\u00eda"},"content":{"rendered":"<p>Estamos trabajando en un proyecto<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"area-de-competencia":[2003,1986,1997],"beneficiario-implicado":[],"coopsudoe-tipo":[1930],"entidades":[2058],"idioma":[2011],"interesado":[1957],"objetivo-especifico":[2114],"paises":[51],"perfil":[],"sector-coop":[],"class_list":["post-33361","coopsudoe","type-coopsudoe","status-publish","hentry","area-de-competencia-envejecimiento-activo","area-de-competencia-innovacion","area-de-competencia-innovacion-social-la-valorizacion-del-patrimonio-y-los-servicios","coopsudoe-tipo-miembro","entidades-grupos-de-interes-incluidas-ongs","idioma-espanol","interesado-formar-parte-de-un-proyecto","objetivo-especifico-os-4-5","paises-espana"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aurelio Garc\u00eda - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/aurelio-garcia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aurelio Garc\u00eda - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"Estamos trabajando en un proyecto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/aurelio-garcia\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/aurelio-garcia\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/aurelio-garcia\\\/\",\"name\":\"Aurelio Garc\u00eda - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\"},\"datePublished\":\"2024-05-16T09:51:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/aurelio-garcia\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/aurelio-garcia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/coopsudoe\\\/aurelio-garcia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aurelio Garc\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aurelio Garc\u00eda - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/aurelio-garcia\/","og_locale":"fr_FR","og_type":"article","og_title":"Aurelio Garc\u00eda - Interreg Sudoe","og_description":"Estamos trabajando en un proyecto","og_url":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/aurelio-garcia\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","og_image":[{"width":344,"height":147,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/aurelio-garcia\/","url":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/aurelio-garcia\/","name":"Aurelio Garc\u00eda - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#website"},"datePublished":"2024-05-16T09:51:14+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/aurelio-garcia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/aurelio-garcia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/fr\/coopsudoe\/aurelio-garcia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Aurelio Garc\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/fr\/#website","url":"https:\/\/interreg-sudoe.eu\/fr\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/coopsudoe\/33361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/coopsudoe"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/types\/coopsudoe"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media?parent=33361"}],"wp:term":[{"taxonomy":"area-de-competencia","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/area-de-competencia?post=33361"},{"taxonomy":"beneficiario-implicado","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/beneficiario-implicado?post=33361"},{"taxonomy":"coopsudoe-tipo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/coopsudoe-tipo?post=33361"},{"taxonomy":"entidades","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/entidades?post=33361"},{"taxonomy":"idioma","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/idioma?post=33361"},{"taxonomy":"interesado","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/interesado?post=33361"},{"taxonomy":"objetivo-especifico","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/objetivo-especifico?post=33361"},{"taxonomy":"paises","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/paises?post=33361"},{"taxonomy":"perfil","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/perfil?post=33361"},{"taxonomy":"sector-coop","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/sector-coop?post=33361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}