{"id":48448,"date":"2025-06-19T09:01:10","date_gmt":"2025-06-19T07:01:10","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/noticia-proyecto\/mas-de-30-stakeholders-participaron-en-una-jornada-tecnica-en-asturias-sobre-el-riesgo-de-contaminacion-por-pfas\/"},"modified":"2026-02-16T13:10:16","modified_gmt":"2026-02-16T12:10:16","slug":"plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies","status":"publish","type":"noticia-proyecto","link":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/","title":{"rendered":"Plus de 30 personnes ont particip\u00e9 \u00e0 une journ\u00e9e technique dans les Asturies sur le risque de contamination par les PFAS"},"content":{"rendered":"<p data-start=\"373\" data-end=\"861\"><em><strong data-start=\"389\" data-end=\"417\">Rioseco, le 12 juin 2025 &#8211; <\/strong><\/em>Le 12 juin dernier, le <strong data-start=\"443\" data-end=\"478\">Centre Culturel Vicente \u00c1lvarez<\/strong> \u00e0 <strong data-start=\"481\" data-end=\"503\">Rioseco (Asturies)<\/strong> a accueilli une <strong data-start=\"520\" data-end=\"551\">journ\u00e9e technique r\u00e9gionale<\/strong> dans le cadre du projet europ\u00e9en <strong data-start=\"585\" data-end=\"599\">ALERT-PFAS<\/strong>, organis\u00e9e par le <strong data-start=\"618\" data-end=\"665\">Gouvernement de la Principaut\u00e9 des Asturies<\/strong>, avec pour objectif de <strong data-start=\"689\" data-end=\"761\">sensibiliser et former sur les risques de contamination par les PFAS<\/strong> (substances perfluoroalkyl\u00e9es et polyfluoroalkyl\u00e9es) dans les milieux naturels, en particulier dans les zones touch\u00e9es par les incendies de for\u00eat.<\/p>\n<p data-start=\"373\" data-end=\"861\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-48432 size-medium\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-5-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-5-300x200.jpg 300w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-5-1024x683.jpg 1024w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-5-768x512.jpg 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-5-1536x1024.jpg 1536w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-5-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p data-start=\"910\" data-end=\"1174\">La journ\u00e9e a r\u00e9uni <strong data-start=\"929\" data-end=\"956\">plus de 30 participants<\/strong> aux profils vari\u00e9s : gestionnaires de l&rsquo;eau, techniciens de l&rsquo;administration, responsables d&rsquo;espaces naturels prot\u00e9g\u00e9s, repr\u00e9sentants des services d&rsquo;urgence, professionnels de l&rsquo;analyse environnementale et chercheurs.<\/p>\n<p data-start=\"1176\" data-end=\"1555\">Au cours de la matin\u00e9e, les experts du projet ont pr\u00e9sent\u00e9 les <strong data-start=\"1239\" data-end=\"1287\">objectifs et premiers r\u00e9sultats d\u2019ALERT-PFAS<\/strong>, en mettant l&rsquo;accent sur les <strong data-start=\"1317\" data-end=\"1393\">risques li\u00e9s \u00e0 l&rsquo;utilisation de mousses anti-incendie contenant des PFAS<\/strong>, leur d\u00e9tection dans l&rsquo;espace SUDOE (Espagne, France et Portugal), ainsi que le d\u00e9veloppement d\u2019un <strong data-start=\"1493\" data-end=\"1554\">outil num\u00e9rique d\u2019\u00e9valuation des risques environnementaux<\/strong>.<\/p>\n<p data-start=\"1163\" data-end=\"1528\"><img decoding=\"async\" class=\"size-medium wp-image-48433 aligncenter\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-6-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-6-300x200.jpg 300w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-6-1024x683.jpg 1024w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-6-768x512.jpg 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-6-1536x1024.jpg 1536w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-6-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p data-start=\"1530\" data-end=\"1801\">Parmi les interventions notables figuraient celle de <strong data-start=\"1610\" data-end=\"1626\">Joana Bastos<\/strong>, repr\u00e9sentant la Universidade NOVA de Lisboa, <strong data-start=\"1673\" data-end=\"1689\">Albert Serra<\/strong> de CETAQUA, ainsi que des repr\u00e9sentants d\u2019<strong data-start=\"1732\" data-end=\"1750\">IDP Ingenier\u00eda<\/strong>. La <strong data-start=\"1755\" data-end=\"1791\">s\u00e9ance d\u2019ouverture et de cl\u00f4ture<\/strong> a \u00e9t\u00e9 assur\u00e9e par <strong data-start=\"1810\" data-end=\"1845\">Alejandro Jes\u00fas Calvo Rodr\u00edguez<\/strong>, Conseiller \u00e0 la Mobilit\u00e9, \u00e0 l&rsquo;Environnement et \u00e0 la Gestion des Urgences du Gouvernement des Asturies, qui a soulign\u00e9 l&rsquo;engagement institutionnel dans la pr\u00e9vention et la gestion des polluants \u00e9mergents comme les PFAS.<br \/>\n<img decoding=\"async\" class=\"size-medium wp-image-48436 aligncenter\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-12-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-12-300x200.jpg 300w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-12-1024x683.jpg 1024w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-12-768x512.jpg 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-12-1536x1024.jpg 1536w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-12-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p data-start=\"1803\" data-end=\"2336\">L\u2019un des moments les plus appr\u00e9ci\u00e9s de la journ\u00e9e a \u00e9t\u00e9 la <strong data-start=\"2126\" data-end=\"2147\">visite de terrain<\/strong> dans l\u2019apr\u00e8s-midi, qui a permis de d\u00e9couvrir deux sites cl\u00e9s de l\u2019\u00e9tude de cas des Asturies. Tout d\u2019abord, une <strong data-start=\"2259\" data-end=\"2302\">zone pilote r\u00e9g\u00e9n\u00e9r\u00e9e apr\u00e8s un incendie<\/strong>, o\u00f9 les travaux r\u00e9alis\u00e9s et leur importance \u00e9cologique ont \u00e9t\u00e9 pr\u00e9sent\u00e9s. Ensuite, les participants se sont rendus \u00e0 la <strong data-start=\"2423\" data-end=\"2473\">station de traitement d\u2019eau potable de Rioseco<\/strong>, o\u00f9 les d\u00e9fis li\u00e9s \u00e0 la qualit\u00e9 de l\u2019eau face aux PFAS ont \u00e9t\u00e9 abord\u00e9s.<\/p>\n<p style=\"text-align: center;\" data-start=\"1803\" data-end=\"2336\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-48438\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-14-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-14-300x200.jpg 300w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-14-1024x683.jpg 1024w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-14-768x512.jpg 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-14-1536x1024.jpg 1536w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-14-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-48445\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-25-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-25-300x200.jpg 300w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-25-1024x683.jpg 1024w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-25-768x512.jpg 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-25-1536x1024.jpg 1536w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-25-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p data-start=\"2338\" data-end=\"2595\">La journ\u00e9e s\u2019est conclue par un espace d\u2019\u00e9change entre les participants, confirmant l\u2019importance d\u2019une collaboration entre administrations, scientifiques et acteurs locaux pour relever de mani\u00e8re coordonn\u00e9e le d\u00e9fi environnemental que repr\u00e9sentent les PFAS.<\/p>\n<p data-start=\"2338\" data-end=\"2595\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-48434\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-10-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-10-300x200.jpg 300w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-10-1024x683.jpg 1024w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-10-768x512.jpg 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-10-1536x1024.jpg 1536w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-10-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-48443\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-23-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-23-300x200.jpg 300w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-23-1024x683.jpg 1024w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-23-768x512.jpg 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-23-1536x1024.jpg 1536w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-23-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-48437\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-13-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-13-300x200.jpg 300w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-13-1024x683.jpg 1024w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-13-768x512.jpg 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-13-1536x1024.jpg 1536w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-13-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rioseco, le 12 juin 2025 &#8211; Le 12 juin dernier, le Centre Culturel Vicente \u00c1lvarez \u00e0 Rioseco (Asturies) a accueilli une journ\u00e9e technique r\u00e9gionale dans le cadre du projet europ\u00e9en ALERT-PFAS, organis\u00e9e par le Gouvernement de la Principaut\u00e9 des Asturies, avec pour objectif de sensibiliser et former sur les risques de contamination par les PFAS [&hellip;]<\/p>\n","protected":false},"author":4724,"featured_media":48441,"parent":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"class_list":["post-48448","noticia-proyecto","type-noticia-proyecto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plus de 30 personnes ont particip\u00e9 \u00e0 une journ\u00e9e technique dans les Asturies sur le risque de contamination par les PFAS - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plus de 30 personnes ont particip\u00e9 \u00e0 une journ\u00e9e technique dans les Asturies sur le risque de contamination par les PFAS - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"Rioseco, le 12 juin 2025 &#8211; Le 12 juin dernier, le Centre Culturel Vicente \u00c1lvarez \u00e0 Rioseco (Asturies) a accueilli une journ\u00e9e technique r\u00e9gionale dans le cadre du projet europ\u00e9en ALERT-PFAS, organis\u00e9e par le Gouvernement de la Principaut\u00e9 des Asturies, avec pour objectif de sensibiliser et former sur les risques de contamination par les PFAS [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-16T12:10:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-21-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\\\/\",\"name\":\"Plus de 30 personnes ont particip\u00e9 \u00e0 une journ\u00e9e technique dans les Asturies sur le risque de contamination par les PFAS - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Alert_ast-21-scaled.jpg\",\"datePublished\":\"2025-06-19T07:01:10+00:00\",\"dateModified\":\"2026-02-16T12:10:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Alert_ast-21-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/Alert_ast-21-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plus de 30 personnes ont particip\u00e9 \u00e0 une journ\u00e9e technique dans les Asturies sur le risque de contamination par les PFAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plus de 30 personnes ont particip\u00e9 \u00e0 une journ\u00e9e technique dans les Asturies sur le risque de contamination par les PFAS - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/","og_locale":"fr_FR","og_type":"article","og_title":"Plus de 30 personnes ont particip\u00e9 \u00e0 une journ\u00e9e technique dans les Asturies sur le risque de contamination par les PFAS - Interreg Sudoe","og_description":"Rioseco, le 12 juin 2025 &#8211; Le 12 juin dernier, le Centre Culturel Vicente \u00c1lvarez \u00e0 Rioseco (Asturies) a accueilli une journ\u00e9e technique r\u00e9gionale dans le cadre du projet europ\u00e9en ALERT-PFAS, organis\u00e9e par le Gouvernement de la Principaut\u00e9 des Asturies, avec pour objectif de sensibiliser et former sur les risques de contamination par les PFAS [&hellip;]","og_url":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","article_modified_time":"2026-02-16T12:10:16+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-21-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/","url":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/","name":"Plus de 30 personnes ont particip\u00e9 \u00e0 une journ\u00e9e technique dans les Asturies sur le risque de contamination par les PFAS - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/#primaryimage"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/#primaryimage"},"thumbnailUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-21-scaled.jpg","datePublished":"2025-06-19T07:01:10+00:00","dateModified":"2026-02-16T12:10:16+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/#primaryimage","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-21-scaled.jpg","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/06\/Alert_ast-21-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/plus-de-30-personnes-ont-participe-a-une-journee-technique-dans-les-asturies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Plus de 30 personnes ont particip\u00e9 \u00e0 une journ\u00e9e technique dans les Asturies sur le risque de contamination par les PFAS"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/fr\/#website","url":"https:\/\/interreg-sudoe.eu\/fr\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/noticia-proyecto\/48448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/noticia-proyecto"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/types\/noticia-proyecto"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/users\/4724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media\/48441"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media?parent=48448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}