{"id":63917,"date":"2026-04-16T09:55:33","date_gmt":"2026-04-16T07:55:33","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/?post_type=noticia-proyecto&#038;p=63917"},"modified":"2026-04-16T10:39:05","modified_gmt":"2026-04-16T08:39:05","slug":"entrepreneur-scaira-javier-urrios-hisperion-aerospace","status":"publish","type":"noticia-proyecto","link":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/","title":{"rendered":"Entrepreneur SCAIRA : Javier Urrios (Hisperion Aerospace)"},"content":{"rendered":"<h2>Rencontrez Javier Urrios, s\u00e9lectionn\u00e9 lors du troisi\u00e8me appel \u00e0 candidatures avec son projet Hisperion Aerospace.<\/h2>\n<h3>Parlez-nous de vous et de votre parcours !<\/h3>\n<div class=\"flex flex-col text-sm pb-25\">\n<section class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:48610b64-2b4f-4a82-a5dd-1bde88d04282-30\" data-testid=\"conversation-turn-62\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"3f8bab16-9121-4e86-96a2-b3a88c131356\" data-message-model-slug=\"gpt-5-3\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word light markdown-new-styling\">\n<p data-start=\"0\" data-end=\"520\">Je m\u2019appelle <a href=\"https:\/\/www.linkedin.com\/in\/javier-urrios\/\" target=\"_blank\" rel=\"noopener\">Javier Urrios<\/a>. Je suis ing\u00e9nieur a\u00e9rospatial et j\u2019oriente ma carri\u00e8re professionnelle vers le domaine spatial. J\u2019ai effectu\u00e9 mes \u00e9tudes d\u2019ing\u00e9nieur \u00e0 S\u00e9ville, puis j\u2019ai eu l\u2019opportunit\u00e9 de m\u2019installer \u00e0 Milan pour suivre un double dipl\u00f4me de master. Au cours de mes \u00e9tudes, j\u2019ai men\u00e9 des travaux de recherche \u00e0 la fois avec l\u2019Universit\u00e9 de S\u00e9ville et le Politecnico di Milano, principalement centr\u00e9s sur l\u2019optimisation des trajectoires de v\u00e9hicules spatiaux \u00e0 l\u2019aide de nouvelles technologies de propulsion.<\/p>\n<p data-start=\"522\" data-end=\"1306\" data-is-last-node=\"\" data-is-only-node=\"\">Par la suite, j\u2019ai travaill\u00e9 sur un projet de R&amp;D pour Indra portant sur la gestion du trafic spatial et les man\u0153uvres d\u2019\u00e9vitement des collisions. Durant cette p\u00e9riode, mes associ\u00e9s et moi avons identifi\u00e9 le m\u00eame probl\u00e8me : il n\u2019existe pas d\u2019outils logiciels commerciaux standards adapt\u00e9s aux entreprises du New Space. Les outils actuels ont \u00e9t\u00e9 con\u00e7us pour de grandes agences et ne r\u00e9pondent pas bien aux besoins des entreprises du New Space, qui sont plus petites, plus agiles, disposent de cycles de d\u00e9veloppement plus rapides et de budgets plus limit\u00e9s. C\u2019est pr\u00e9cis\u00e9ment pour cette raison que nous avons d\u00e9cid\u00e9 de d\u00e9velopper un logiciel de simulation spatiale adapt\u00e9 aux besoins des entreprises du New Space. <a href=\"https:\/\/www.hisperion.com\/orbita\/\" target=\"_blank\" rel=\"noopener\">Ce logiciel s\u2019appelle Orbita et est d\u00e9velopp\u00e9 par Hisperion Aerospace.<\/a><\/p>\n<p><iframe title=\"Orbita | A new Paradigm in Space Simulation\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/Ns2hytGVsho?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<h3>Comment avez-vous d\u00e9couvert SCAIRA ?<\/h3>\n<div class=\"flex flex-col text-sm pb-25\">\n<section class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:48610b64-2b4f-4a82-a5dd-1bde88d04282-31\" data-testid=\"conversation-turn-64\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"97e49981-0d44-4d6d-a5d0-69d019be0069\" data-message-model-slug=\"gpt-5-3\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word light markdown-new-styling\">\n<p data-start=\"0\" data-end=\"264\" data-is-last-node=\"\" data-is-only-node=\"\">J\u2019ai eu l\u2019occasion de rencontrer Silvia de los Santos, responsable du secteur a\u00e9rospatial au <strong>CTA<\/strong>, lors de NISE 2025 \u00e0 S\u00e9ville. Nous y avons \u00e9tabli un premier contact et, par la suite, elle nous a inform\u00e9s de l\u2019existence de ce programme, ce que j\u2019appr\u00e9cie beaucoup.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<h3>\u00c0 quel stade se trouve actuellement votre start-up ?<\/h3>\n<div class=\"flex flex-col text-sm pb-25\">\n<section class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:48610b64-2b4f-4a82-a5dd-1bde88d04282-32\" data-testid=\"conversation-turn-66\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"77f34a01-3659-4c49-bebf-be56cc383b03\" data-message-model-slug=\"gpt-5-3\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word light markdown-new-styling\">\n<p data-start=\"0\" data-end=\"430\" data-is-last-node=\"\" data-is-only-node=\"\"><strong>Nous disposons actuellement d\u2019une premi\u00e8re traction sur le march\u00e9.<\/strong> Nous avons d\u00e9velopp\u00e9 le MVP il y a moins d\u2019un an et, depuis lors, nous avons continu\u00e9 \u00e0 am\u00e9liorer notre logiciel afin d\u2019atteindre une version commerciale pr\u00eate \u00e0 \u00eatre d\u00e9ploy\u00e9e et facilement scalable. Au cours de cette p\u00e9riode de d\u00e9veloppement, nous avons d\u00e9j\u00e0 obtenu deux clients payants, ce que nous consid\u00e9rons comme un signal clair de validation par le march\u00e9.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<h3>Quelle est la nature de votre projet et quel probl\u00e8me vise-t-il \u00e0 r\u00e9soudre ?<\/h3>\n<p data-start=\"0\" data-end=\"605\"><strong>Notre objectif final est de d\u00e9mocratiser l\u2019acc\u00e8s \u00e0 l\u2019espace gr\u00e2ce au d\u00e9veloppement d\u2019Orbita<\/strong>, une plateforme europ\u00e9enne de simulation spatiale \u00e0 haute fid\u00e9lit\u00e9 con\u00e7ue sp\u00e9cifiquement pour le secteur du New Space. Orbita couvre l\u2019ensemble du cycle de vie d\u2019un satellite, depuis la phase de conception jusqu\u2019aux op\u00e9rations en orbite et \u00e0 la fin de vie. Elle mod\u00e9lise la dynamique, les capteurs et les actionneurs, et int\u00e8gre de mani\u00e8re unique la simulation des cam\u00e9ras embarqu\u00e9es \u00e0 bord des satellites afin de valider des syst\u00e8mes de contr\u00f4le bas\u00e9s sur l\u2019intelligence artificielle et la vision par ordinateur.<\/p>\n<p data-start=\"607\" data-end=\"1579\"><strong data-start=\"607\" data-end=\"621\">Probl\u00e8me :<\/strong> Traditionnellement, la simulation spatiale repose sur deux approches principales : des solutions commerciales \u00e9tablies, co\u00fbteuses et peu adaptables aux PME, ou le d\u00e9veloppement \u00e0 partir de z\u00e9ro de code ad hoc, co\u00fbteux et sujet aux erreurs. En outre, les outils actuels n\u2019int\u00e8grent pas correctement les nouveaux besoins tels que l\u2019intelligence artificielle et l\u2019apprentissage automatique (AI\/ML), ni les techniques les plus avanc\u00e9es de guidage, navigation et contr\u00f4le (GNC). Orbita supprime cette contrainte en proposant une interface graphique utilisateur (GUI) accessible, bas\u00e9e sur C++, ainsi qu\u2019un flux de travail structur\u00e9 autour de diagrammes fonctionnels qui r\u00e9duit fortement les besoins en programmation intensive. Elle contribue \u00e9galement directement \u00e0 la durabilit\u00e9 spatiale en permettant l\u2019int\u00e9gration de principes d\u2019\u00e9co-conception et la validation de man\u0153uvres d\u2019\u00e9vitement de collision (CAM), afin de limiter la prolif\u00e9ration des d\u00e9bris spatiaux.<\/p>\n<p data-start=\"1581\" data-end=\"2258\" data-is-last-node=\"\" data-is-only-node=\"\"><strong data-start=\"1581\" data-end=\"1619\">Objectifs et vision \u00e0 long terme :<\/strong> \u00c0 court terme, notre objectif est d\u2019achever Orbita 1.0, de recruter entre 10 et 20 PME europ\u00e9ennes comme clients pilotes et de valider notre mod\u00e8le tarifaire. Dans les prochaines ann\u00e9es, nous ambitionnons de jouer un r\u00f4le de premier plan dans la r\u00e9volution du New Space europ\u00e9en du point de vue logiciel, en devenant le simulateur de missions de r\u00e9f\u00e9rence au sein de l\u2019Union europ\u00e9enne. \u00c0 l\u2019horizon 2029, nous pr\u00e9voyons de nous d\u00e9velopper \u00e0 l\u2019\u00e9chelle de l\u2019UE, des \u00c9tats-Unis et de l\u2019Asie, en nous appuyant sur des licences individuelles et institutionnelles afin d\u2019atteindre plusieurs millions d\u2019euros de revenus annuels r\u00e9currents (ARR).<\/p>\n<p data-start=\"1581\" data-end=\"2258\" data-is-last-node=\"\" data-is-only-node=\"\"><img decoding=\"async\" class=\"size-medium wp-image-63926 alignright\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/logo_with_name_hd-1-300x96.png\" alt=\"\" width=\"300\" height=\"96\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/logo_with_name_hd-1-300x96.png 300w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/logo_with_name_hd-1-768x245.png 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/logo_with_name_hd-1.png 926w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3>Quels sont les services de SCAIRA que vous avez choisis ?<\/h3>\n<p data-start=\"0\" data-end=\"46\">Nous avons s\u00e9lectionn\u00e9 les services suivants :<\/p>\n<p data-start=\"48\" data-end=\"772\" data-is-last-node=\"\" data-is-only-node=\"\"><strong data-start=\"48\" data-end=\"63\">Service 2 :<\/strong> Formation en propri\u00e9t\u00e9 intellectuelle.<br data-start=\"102\" data-end=\"105\" data-is-only-node=\"\" \/><strong data-start=\"105\" data-end=\"120\">Service 3 :<\/strong> Strat\u00e9gie financi\u00e8re orient\u00e9e vers l\u2019innovation et la fabrication durable, ainsi qu\u2019identification des opportunit\u00e9s de financement priv\u00e9 pour les start-ups et les innovations vertes.<br data-start=\"303\" data-end=\"306\" \/><strong data-start=\"306\" data-end=\"321\">Service 4 :<\/strong> Opportunit\u00e9s de financement public national pour les start-ups et les innovations vertes.<br data-start=\"411\" data-end=\"414\" \/><strong data-start=\"414\" data-end=\"430\">Service 12 :<\/strong> \u00c9tude de march\u00e9 et identification des clients cibles.<br data-start=\"484\" data-end=\"487\" \/><strong data-start=\"487\" data-end=\"510\">Services 13 et 14 :<\/strong> Pr\u00e9paration du pitch pour une pr\u00e9sentation devant des acteurs industriels et des investisseurs, enregistrement sur LOOM, et organisation de rencontres B2B entre start-ups et entreprises industrielles ainsi que de rencontres B2F entre start-ups et investisseurs.<\/p>\n<h3 data-start=\"122\" data-end=\"196\">Quels sont vos objectifs \u00e0 court terme dans le cadre du programme d\u2019acc\u00e9l\u00e9ration ?<\/h3>\n<p data-start=\"0\" data-end=\"515\"><strong>Nous consid\u00e9rons le programme SCAIRA comme un m\u00e9canisme de soutien pratique permettant de renforcer des domaines cl\u00e9s de notre activit\u00e9 tout en restant concentr\u00e9s sur le d\u00e9veloppement du produit.<\/strong> Gr\u00e2ce \u00e0 notre participation, nous esp\u00e9rons obtenir des orientations concr\u00e8tes en mati\u00e8re de strat\u00e9gies de propri\u00e9t\u00e9 intellectuelle n\u00e9cessaires pour prot\u00e9ger notre logiciel et nos algorithmes avant de passer \u00e0 l\u2019\u00e9chelle ; nous pr\u00e9parer efficacement \u00e0 notre prochaine lev\u00e9e de fonds d\u2019amor\u00e7age gr\u00e2ce \u00e0 des formations et des s\u00e9minaires cibl\u00e9s ; et b\u00e9n\u00e9ficier de l\u2019acc\u00e8s au r\u00e9seau d\u2019investisseurs et de partenaires industriels potentiels du programme. \u00c0 court terme, ce soutien nous permettra de combler certaines lacunes dans des domaines non techniques et de valider notre mod\u00e8le \u00e9conomique ainsi que notre strat\u00e9gie tarifaire avec un accompagnement professionnel. En outre, nous pr\u00e9voyons de tirer pleinement parti des rencontres B2B organis\u00e9es afin d\u2019\u00e9tablir des contacts structur\u00e9s avec d\u2019autres PME du secteur a\u00e9rospatial et avec des clients potentiels.<\/p>\n<section class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:cc5c3205-6a9d-4e50-a8aa-7528799d14c5-56\" data-testid=\"conversation-turn-56\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"35cf7504-aa63-461c-82e5-e004ebd95faf\" data-message-model-slug=\"gpt-5-3\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word light markdown-new-styling\">\n<h3 data-start=\"0\" data-end=\"70\">Quel est votre march\u00e9 cible et quels besoins cherchez-vous \u00e0 couvrir ?<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\">\n<p data-start=\"0\" data-end=\"498\"><strong>Notre march\u00e9 cible est constitu\u00e9 des PME du secteur New Space et, \u00e0 terme, \u00e9galement des agences spatiales.<\/strong> \u00c0 court terme, nous pr\u00e9voyons de recruter entre 10 et 20 PME en Espagne et dans l\u2019Union europ\u00e9enne comme clients pilotes. \u00c0 plus long terme, nous envisageons de nous d\u00e9velopper \u00e0 l\u2019\u00e9chelle de l\u2019UE, des \u00c9tats-Unis et de l\u2019Asie, en nous appuyant sur des licences individuelles et institutionnelles en volume, ainsi que sur des int\u00e9grations avec des op\u00e9rateurs et de grands acteurs du secteur.<\/p>\n<p data-start=\"500\" data-end=\"1050\">En ce qui concerne les besoins des clients, la simulation constitue un \u00e9l\u00e9ment essentiel des projets spatiaux, car il n\u2019est pas possible d\u2019effectuer des corrections physiques en orbite. Cela positionne notre produit comme une solution cl\u00e9 dans les phases amont de la cha\u00eene de valeur du secteur spatial. Aujourd\u2019hui, les acteurs du New Space d\u00e9veloppent soit du code ad hoc co\u00fbteux, long \u00e0 produire et sujet aux erreurs, soit s\u2019appuient sur des suites logicielles commerciales \u00e9tablies, caract\u00e9ris\u00e9es par des co\u00fbts \u00e9lev\u00e9s et une adaptabilit\u00e9 limit\u00e9e.<\/p>\n<p data-start=\"1052\" data-end=\"1494\">En outre, les outils existants n\u2019int\u00e8grent pas pleinement certaines capacit\u00e9s devenues indispensables dans un secteur en \u00e9volution rapide, telles que l\u2019int\u00e9gration fluide de l\u2019intelligence artificielle et de l\u2019apprentissage automatique (AI\/ML), la simulation de syst\u00e8mes de vision par cam\u00e9ras satellitaires \u00e0 haute fid\u00e9lit\u00e9, ou encore la possibilit\u00e9 de mod\u00e9liser et de valider des techniques avanc\u00e9es de guidage, navigation et contr\u00f4le (GNC).<\/p>\n<p data-start=\"1496\" data-end=\"1824\" data-is-last-node=\"\" data-is-only-node=\"\">Notre solution, Orbita, supprime cette contrainte en proposant une interface graphique simple d\u2019utilisation, un flux de travail bas\u00e9 sur des diagrammes fonctionnels et des outils de scripting permettant la simulation de la dynamique et des op\u00e9rations des v\u00e9hicules spatiaux sans n\u00e9cessiter d\u2019importants efforts de programmation.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<h3 data-olk-copy-source=\"MailCompose\">Quels sont vos principaux d\u00e9fis actuels ?<\/h3>\n<div class=\"flex flex-col text-sm pb-25\">\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:ca4a043b-71d3-4697-8997-9d9732b0fb9f-17\" data-testid=\"conversation-turn-36\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] @w-sm\/main:[--thread-content-margin:--spacing(6)] @w-lg\/main:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"37c9c9d7-8bb9-4354-9404-afbc1bac9fed\" data-message-model-slug=\"gpt-5-2\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\n<p data-start=\"0\" data-end=\"285\">Bien que notre solution technique vise \u00e0 r\u00e9pondre au d\u00e9fi sectoriel \u00ab \u00c9conomie circulaire dans les industries a\u00e9rospatiale et automobile \u00bb (D\u00e9fi SCAIRA 5),<strong> nos principaux d\u00e9fis internes en tant que start-up concernent actuellement des lacunes en mati\u00e8re de comp\u00e9tences non techniques<\/strong> :<\/p>\n<ul data-start=\"287\" data-end=\"975\" data-is-last-node=\"\" data-is-only-node=\"\">\n<li data-section-id=\"5zcnfd\" data-start=\"287\" data-end=\"433\">Nous devons d\u00e9finir des strat\u00e9gies de propri\u00e9t\u00e9 intellectuelle afin de prot\u00e9ger notre logiciel et nos algorithmes avant de passer \u00e0 l\u2019\u00e9chelle.<\/li>\n<li data-section-id=\"14l8hke\" data-start=\"434\" data-end=\"530\">Nous travaillons \u00e0 la validation de notre mod\u00e8le \u00e9conomique et de notre strat\u00e9gie tarifaire.<\/li>\n<li data-section-id=\"1h4ve8\" data-start=\"531\" data-end=\"690\">Nous pr\u00e9parons actuellement notre prochaine lev\u00e9e de fonds d\u2019amor\u00e7age et devons \u00e9tablir des contacts avec des investisseurs et des partenaires industriels.<\/li>\n<li data-section-id=\"1sfqa4o\" data-start=\"691\" data-end=\"975\" data-is-last-node=\"\">Nous devons renforcer la notori\u00e9t\u00e9 de notre marque et \u00e9largir notre r\u00e9seau au-del\u00e0 de notre \u00e9cosyst\u00e8me local, afin d\u2019initier des \u00e9changes susceptibles de d\u00e9boucher sur des relations commerciales ou des projets pilotes en dehors de l\u2019Espagne et, potentiellement, au-del\u00e0 de l\u2019Europe.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<h3>Avez-vous d\u00e9j\u00e0 une \u00e9quipe ?<\/h3>\n<p>Oui, <a href=\"https:\/\/www.hisperion.com\/team\/\" target=\"_blank\" rel=\"noopener\">Hisperion Aerospace S.L. a \u00e9t\u00e9 fond\u00e9e par trois ing\u00e9nieurs a\u00e9rospatiaux<\/a>. En ce qui me concerne, en tant que CEO, je suis responsable de la strat\u00e9gie et de la coordination du projet, en apportant une vision entrepreneuriale ainsi que des comp\u00e9tences en communication. <strong>Jos\u00e9 Antonio Rebollo<\/strong>, notre CTO, est charg\u00e9 du d\u00e9veloppement du logiciel et de l\u2019ing\u00e9nierie des syst\u00e8mes haute performance, avec une solide base en recherche. De son c\u00f4t\u00e9, <strong>Joaqu\u00edn Gonz\u00e1lez L\u00f3pez-Cepero<\/strong>, COO de l\u2019entreprise, supervise l\u2019organisation op\u00e9rationnelle et l\u2019ex\u00e9cution des activit\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rencontrez Javier Urrios, s\u00e9lectionn\u00e9 lors du troisi\u00e8me appel \u00e0 candidatures avec son projet Hisperion Aerospace. Parlez-nous de vous et de votre parcours ! Je m\u2019appelle Javier Urrios. Je suis ing\u00e9nieur a\u00e9rospatial et j\u2019oriente ma carri\u00e8re professionnelle vers le domaine spatial. J\u2019ai effectu\u00e9 mes \u00e9tudes d\u2019ing\u00e9nieur \u00e0 S\u00e9ville, puis j\u2019ai eu l\u2019opportunit\u00e9 de m\u2019installer \u00e0 Milan [&hellip;]<\/p>\n","protected":false},"author":5002,"featured_media":63914,"parent":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"class_list":["post-63917","noticia-proyecto","type-noticia-proyecto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrepreneur SCAIRA : Javier Urrios (Hisperion Aerospace) - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrepreneur SCAIRA : Javier Urrios (Hisperion Aerospace) - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"Rencontrez Javier Urrios, s\u00e9lectionn\u00e9 lors du troisi\u00e8me appel \u00e0 candidatures avec son projet Hisperion Aerospace. Parlez-nous de vous et de votre parcours ! Je m\u2019appelle Javier Urrios. Je suis ing\u00e9nieur a\u00e9rospatial et j\u2019oriente ma carri\u00e8re professionnelle vers le domaine spatial. J\u2019ai effectu\u00e9 mes \u00e9tudes d\u2019ing\u00e9nieur \u00e0 S\u00e9ville, puis j\u2019ai eu l\u2019opportunit\u00e9 de m\u2019installer \u00e0 Milan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T08:39:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/3CALLJ1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\\\/\",\"name\":\"Entrepreneur SCAIRA : Javier Urrios (Hisperion Aerospace) - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3CALLJ1.jpg\",\"datePublished\":\"2026-04-16T07:55:33+00:00\",\"dateModified\":\"2026-04-16T08:39:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3CALLJ1.jpg\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3CALLJ1.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrepreneur SCAIRA : Javier Urrios (Hisperion Aerospace)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrepreneur SCAIRA : Javier Urrios (Hisperion Aerospace) - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/","og_locale":"fr_FR","og_type":"article","og_title":"Entrepreneur SCAIRA : Javier Urrios (Hisperion Aerospace) - Interreg Sudoe","og_description":"Rencontrez Javier Urrios, s\u00e9lectionn\u00e9 lors du troisi\u00e8me appel \u00e0 candidatures avec son projet Hisperion Aerospace. Parlez-nous de vous et de votre parcours ! Je m\u2019appelle Javier Urrios. Je suis ing\u00e9nieur a\u00e9rospatial et j\u2019oriente ma carri\u00e8re professionnelle vers le domaine spatial. J\u2019ai effectu\u00e9 mes \u00e9tudes d\u2019ing\u00e9nieur \u00e0 S\u00e9ville, puis j\u2019ai eu l\u2019opportunit\u00e9 de m\u2019installer \u00e0 Milan [&hellip;]","og_url":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","article_modified_time":"2026-04-16T08:39:05+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/3CALLJ1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/","url":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/","name":"Entrepreneur SCAIRA : Javier Urrios (Hisperion Aerospace) - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/#primaryimage"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/#primaryimage"},"thumbnailUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/3CALLJ1.jpg","datePublished":"2026-04-16T07:55:33+00:00","dateModified":"2026-04-16T08:39:05+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/#primaryimage","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/3CALLJ1.jpg","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/3CALLJ1.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/entrepreneur-scaira-javier-urrios-hisperion-aerospace\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Entrepreneur SCAIRA : Javier Urrios (Hisperion Aerospace)"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/fr\/#website","url":"https:\/\/interreg-sudoe.eu\/fr\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/noticia-proyecto\/63917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/noticia-proyecto"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/types\/noticia-proyecto"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/users\/5002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media\/63914"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media?parent=63917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}