{"id":68373,"date":"2026-06-09T14:33:12","date_gmt":"2026-06-09T12:33:12","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/"},"modified":"2026-06-09T15:55:17","modified_gmt":"2026-06-09T13:55:17","slug":"thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion","status":"publish","type":"noticia-proyecto","link":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/","title":{"rendered":"ThermEcoWat franchit une \u00e9tape cl\u00e9 \u00e0 Madrid : les sites pilotes pr\u00e9sentent leurs premiers plans d\u2019action pour l\u2019adaptation"},"content":{"rendered":"<p data-start=\"7837\" data-end=\"8037\">Du 19 au 21 mai 2026, les partenaires de ThermEcoWat se sont r\u00e9unis \u00e0 Madrid (Espagne), accueillis par le CN IGME-CSIC, pour le 4e et dernier Atelier Transnational du projet avant sa phase de cl\u00f4ture.<\/p>\n<p data-start=\"8039\" data-end=\"8404\">Pendant trois jours d\u2019\u00e9changes, de sessions techniques et de discussions collectives, l\u2019atelier a r\u00e9uni partenaires scientifiques, autorit\u00e9s locales et acteurs des territoires thermaux autour d\u2019un objectif commun : renforcer la r\u00e9silience des \u00e9cosyst\u00e8mes li\u00e9s aux eaux thermales et accompagner les territoires thermaux dans leur adaptation au changement climatique.<\/p>\n<h4 data-section-id=\"15czd7y\" data-start=\"820\" data-end=\"867\"><span style=\"color: #99cc00;\">Trois sites pilotes, trois trajectoires d\u2019adaptation<\/span><\/h4>\n<p data-start=\"869\" data-end=\"1001\">Chacun des trois territoires pilotes a pr\u00e9sent\u00e9 les progr\u00e8s r\u00e9alis\u00e9s au cours des derniers mois gr\u00e2ce \u00e0 la m\u00e9thodologie ThermEcoWat :<\/p>\n<p data-start=\"1003\" data-end=\"1092\">\u2022 S\u00e3o Pedro do Sul (Portugal)<br data-start=\"1032\" data-end=\"1035\" \/>\u2022 Caldes de Montbui (Espagne)<br data-start=\"1063\" data-end=\"1066\" \/>\u2022 Chaudes-Aigues (France)<\/p>\n<figure id=\"attachment_68303\" aria-describedby=\"caption-attachment-68303\" style=\"width: 366px\" class=\"wp-caption alignleft\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-68303\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Presentation-of-Chaudes-Aigues-Pilot-site-progress-871x1024.jpeg\" alt=\"Presentation of progress at the Chaudes-Aigues pilot site\" width=\"366\" height=\"430\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Presentation-of-Chaudes-Aigues-Pilot-site-progress-871x1024.jpeg 871w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Presentation-of-Chaudes-Aigues-Pilot-site-progress-255x300.jpeg 255w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Presentation-of-Chaudes-Aigues-Pilot-site-progress-768x903.jpeg 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Presentation-of-Chaudes-Aigues-Pilot-site-progress.jpeg 1219w\" sizes=\"(max-width: 366px) 100vw, 366px\" \/><figcaption id=\"caption-attachment-68303\" class=\"wp-caption-text\"><em>Pr\u00e9sentation de l&rsquo;\u00e9tat d&rsquo;avancement du cas pilote Chaudes-Aigues par M. Brousse, Maire<\/em><\/figcaption><\/figure>\n<p data-start=\"1094\" data-end=\"1325\">L\u2019atelier a marqu\u00e9 une \u00e9tape importante du projet, puisque les trois sites pilotes ont pr\u00e9sent\u00e9 une premi\u00e8re version consolid\u00e9e de leurs Plans d\u2019Action et d\u2019Adaptation, actuellement en cours de finalisation et de d\u00e9veloppement.<\/p>\n<p data-start=\"8919\" data-end=\"8991\">Ces plans sont le r\u00e9sultat d\u2019un processus pluridisciplinaire combinant :<\/p>\n<p data-start=\"8993\" data-end=\"9255\">\u2022 diagnostic territorial,<br data-start=\"9018\" data-end=\"9021\" \/>\u2022 projections climatiques,<br data-start=\"9047\" data-end=\"9050\" \/>\u2022 analyses hydrog\u00e9ologiques et environnementales,<br data-start=\"9099\" data-end=\"9102\" \/>\u2022 consid\u00e9rations socio-\u00e9conomiques,<br data-start=\"9137\" data-end=\"9140\" \/>\u2022 \u00e9valuation r\u00e9glementaire,<br data-start=\"9167\" data-end=\"9170\" \/>\u2022 analyse de solutions alternatives,<br data-start=\"9206\" data-end=\"9209\" \/>\u2022 et hi\u00e9rarchisation des mesures d\u2019adaptation.<\/p>\n<p data-start=\"1665\" data-end=\"1886\">Un \u00e9l\u00e9ment central de ce processus est le Graphe de Connaissances ThermEcoWat (TEW KG), d\u00e9velopp\u00e9 pour structurer et connecter des donn\u00e9es territoriales h\u00e9t\u00e9rog\u00e8nes et soutenir la prise de d\u00e9cision gr\u00e2ce \u00e0 une approche int\u00e9gr\u00e9e.<\/p>\n<h3 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h3>\n<h3 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h3>\n<figure id=\"attachment_68302\" aria-describedby=\"caption-attachment-68302\" style=\"width: 531px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\" wp-image-68302\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Workshop-Madrid-3-1024x768.jpeg\" alt=\"ThermEcoWat Workshop in Madrid\" width=\"531\" height=\"398\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Workshop-Madrid-3-1024x768.jpeg 1024w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Workshop-Madrid-3-300x225.jpeg 300w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Workshop-Madrid-3-768x576.jpeg 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Workshop-Madrid-3-1536x1152.jpeg 1536w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Workshop-Madrid-3.jpeg 1980w\" sizes=\"(max-width: 531px) 100vw, 531px\" \/><figcaption id=\"caption-attachment-68302\" class=\"wp-caption-text\"><em>Workshop ThermEcoWat\u00a0 \u00e0 Madrid<\/em><\/figcaption><\/figure>\n<figure id=\"attachment_68371\" aria-describedby=\"caption-attachment-68371\" style=\"width: 639px\" class=\"wp-caption alignright\"><img decoding=\"async\" class=\" wp-image-68371\" src=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Presentation-of-Caldes-de-Montbui-Pilot-site-progress-300x187.jpeg\" alt=\"Presentaci\u00f3n del estado de avance de la planta piloto de Caldes de Montbui\" width=\"639\" height=\"398\" srcset=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Presentation-of-Caldes-de-Montbui-Pilot-site-progress-300x187.jpeg 300w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Presentation-of-Caldes-de-Montbui-Pilot-site-progress-1024x640.jpeg 1024w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Presentation-of-Caldes-de-Montbui-Pilot-site-progress-768x480.jpeg 768w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Presentation-of-Caldes-de-Montbui-Pilot-site-progress-1536x960.jpeg 1536w, https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/Presentation-of-Caldes-de-Montbui-Pilot-site-progress.jpeg 1698w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/><figcaption id=\"caption-attachment-68371\" class=\"wp-caption-text\"><em>Pr\u00e9sentation de l&rsquo;\u00e9tat d&rsquo;avancement du cas pilote de Caldes de Montbui, par Isidre Pineda Moncusi, Maire\u00a0<\/em><\/figcaption><\/figure>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h4>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h4>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h4>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h4>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h4>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h4>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h4>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h4>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h4>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h4>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><\/h4>\n<h4 data-section-id=\"bwz46e\" data-start=\"1888\" data-end=\"1919\"><span style=\"color: #99cc00;\">Du diagnostic \u00e0 l&rsquo;action<\/span><\/h4>\n<p data-start=\"9517\" data-end=\"9671\">L\u2019atelier de Madrid a permis aux partenaires de d\u00e9montrer comment les connaissances scientifiques peuvent soutenir des strat\u00e9gies territoriales concr\u00e8tes.<\/p>\n<p data-start=\"9673\" data-end=\"9728\">Pour chaque cas pilote, les discussions ont port\u00e9 sur :<\/p>\n<p data-start=\"9730\" data-end=\"9961\">\u2022 l\u2019analyse des ressources et des sc\u00e9narios futurs,<br data-start=\"9781\" data-end=\"9784\" \/>\u2022 l\u2019utilisation des donn\u00e9es du TEW KG pour l\u2019\u00e9valuation des solutions,<br data-start=\"9854\" data-end=\"9857\" \/>\u2022 les crit\u00e8res de faisabilit\u00e9 et de priorisation,<br data-start=\"9906\" data-end=\"9909\" \/>\u2022 et la pr\u00e9paration de plans d\u2019action op\u00e9rationnels.<\/p>\n<p data-start=\"9963\" data-end=\"10266\">Les plans d\u2019adaptation actuellement en cours d\u2019\u00e9laboration visent non seulement \u00e0 prot\u00e9ger les ressources thermales, mais aussi \u00e0 renforcer la r\u00e9silience territoriale gr\u00e2ce \u00e0 une meilleure gouvernance, \u00e0 la transition \u00e9nerg\u00e9tique, \u00e0 une gestion durable des ressources et \u00e0 la diversification \u00e9conomique.<\/p>\n<h4 data-section-id=\"czcgso\" data-start=\"2619\" data-end=\"2665\"><span style=\"color: #99cc00;\">Poursuite de l&rsquo;\u00e9laboration du Livre Blanc de ThermEcoWat<\/span><\/h4>\n<p data-start=\"10327\" data-end=\"10476\">Madrid a \u00e9galement constitu\u00e9 une \u00e9tape importante dans la pr\u00e9paration de l\u2019un des principaux livrables finaux du projet : le Livre Blanc ThermEcoWat.<\/p>\n<p data-start=\"10478\" data-end=\"10762\">Con\u00e7u comme un guide m\u00e9thodologique destin\u00e9 aux territoires thermaux, le Livre Blanc capitalisera les enseignements tir\u00e9s tout au long du projet et proposera un cadre transf\u00e9rable pour accompagner les d\u00e9cideurs dans la construction de strat\u00e9gies d\u2019adaptation au changement climatique.<\/p>\n<p data-start=\"10764\" data-end=\"11060\">Au-del\u00e0 de la simple pr\u00e9sentation des r\u00e9sultats du projet, le Livre Blanc vise \u00e0 relier connaissances scientifiques, m\u00e9canismes de gouvernance, r\u00e9alit\u00e9s territoriales et processus d\u00e9cisionnels au sein d\u2019une m\u00e9thodologie pratique susceptible d\u2019inspirer les territoires thermaux \u00e0 travers l\u2019Europe.<\/p>\n<h4 data-section-id=\"18pavnf\" data-start=\"3415\" data-end=\"3441\"><span style=\"color: #99cc00;\">Cap sur Bruxelles<\/span><\/h4>\n<p data-start=\"11085\" data-end=\"11192\">Cet atelier cl\u00f4ture le cycle des ateliers transnationaux de ThermEcoWat et ouvre la phase finale du projet.<\/p>\n<p data-start=\"11194\" data-end=\"11371\">La prochaine \u00e9tape majeure sera l\u2019\u00e9v\u00e9nement final de ThermEcoWat \u00e0 Bruxelles, au cours duquel seront pr\u00e9sent\u00e9s les r\u00e9sultats consolid\u00e9s ainsi que les livrables finaux du projet.<\/p>\n<p data-start=\"11373\" data-end=\"11586\">Le consortium souhaite remercier chaleureusement le CN IGME-CSIC pour l\u2019accueil et l\u2019organisation de cet atelier, ainsi que l\u2019ensemble des partenaires du projet pour leur engagement et leur collaboration continus.<\/p>\n<p data-start=\"11588\" data-end=\"11671\" data-is-last-node=\"\" data-is-only-node=\"\">Ensemble, nous construisons des territoires thermaux plus r\u00e9silients pour l\u2019avenir.<\/p>\n<p data-start=\"3892\" data-end=\"3973\"><strong>Art\u00edculos de prensa sobre los sitios piloto :<\/strong><\/p>\n<p data-start=\"3892\" data-end=\"3973\"><a href=\"https:\/\/www.caldesdemontbui.cat\/actualitat\/noticies\/ajuntament-i-balnearis-signen-un-conveni-per-a-la-gestio-i-repartiment-de-laigua-termal-a-caldes-de-montbui.html\">Site pilote de Caldes de Montbui: la Mairie et les \u00e9tablissements thermaux signent un accord pour la gestion et l&rsquo;approvisionnement en eau thermale \u00e0 Caldes de Montbui<\/a><\/p>\n<p data-start=\"3892\" data-end=\"3973\"><a href=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/MT_Clermont_Ferrand_20260603_26_page-0001.jpg\">Chaudes-Aigues mise sur ses ressources naturelles<\/a><\/p>\n<p data-start=\"3892\" data-end=\"3973\"><a href=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/article-Chaudes-Aigues_l-Est-eclair.jpg\">Chaudes-Aigues, ville thermale du Cantal, explore de nouvelles voies pour pr\u00e9server et valoriser ses sources d&rsquo;eau chaude<\/a><\/p>\n<p data-start=\"3892\" data-end=\"3973\">\n","protected":false},"excerpt":{"rendered":"<p>Du 19 au 21 mai 2026, les partenaires de ThermEcoWat se sont r\u00e9unis \u00e0 Madrid (Espagne), accueillis par le CN IGME-CSIC, pour le 4e et dernier Atelier Transnational du projet avant sa phase de cl\u00f4ture.<\/p>\n","protected":false},"author":6514,"featured_media":68301,"parent":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"class_list":["post-68373","noticia-proyecto","type-noticia-proyecto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ThermEcoWat franchit une \u00e9tape cl\u00e9 \u00e0 Madrid : les sites pilotes pr\u00e9sentent leurs premiers plans d\u2019action pour l\u2019adaptation - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ThermEcoWat franchit une \u00e9tape cl\u00e9 \u00e0 Madrid : les sites pilotes pr\u00e9sentent leurs premiers plans d\u2019action pour l\u2019adaptation - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"Du 19 au 21 mai 2026, les partenaires de ThermEcoWat se sont r\u00e9unis \u00e0 Madrid (Espagne), accueillis par le CN IGME-CSIC, pour le 4e et dernier Atelier Transnational du projet avant sa phase de cl\u00f4ture.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-09T13:55:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/workshop-Madrid-Groupe2-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1307\" \/>\n\t<meta property=\"og:image:height\" content=\"743\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\\\/\",\"name\":\"ThermEcoWat franchit une \u00e9tape cl\u00e9 \u00e0 Madrid : les sites pilotes pr\u00e9sentent leurs premiers plans d\u2019action pour l\u2019adaptation - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/workshop-Madrid-Groupe2-1.jpeg\",\"datePublished\":\"2026-06-09T12:33:12+00:00\",\"dateModified\":\"2026-06-09T13:55:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/workshop-Madrid-Groupe2-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/workshop-Madrid-Groupe2-1.jpeg\",\"width\":1307,\"height\":743,\"caption\":\"ThermEcoWat Workshop in Madrid\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/noticia-proyecto\\\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ThermEcoWat franchit une \u00e9tape cl\u00e9 \u00e0 Madrid : les sites pilotes pr\u00e9sentent leurs premiers plans d\u2019action pour l\u2019adaptation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ThermEcoWat franchit une \u00e9tape cl\u00e9 \u00e0 Madrid : les sites pilotes pr\u00e9sentent leurs premiers plans d\u2019action pour l\u2019adaptation - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/","og_locale":"fr_FR","og_type":"article","og_title":"ThermEcoWat franchit une \u00e9tape cl\u00e9 \u00e0 Madrid : les sites pilotes pr\u00e9sentent leurs premiers plans d\u2019action pour l\u2019adaptation - Interreg Sudoe","og_description":"Du 19 au 21 mai 2026, les partenaires de ThermEcoWat se sont r\u00e9unis \u00e0 Madrid (Espagne), accueillis par le CN IGME-CSIC, pour le 4e et dernier Atelier Transnational du projet avant sa phase de cl\u00f4ture.","og_url":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","article_modified_time":"2026-06-09T13:55:17+00:00","og_image":[{"width":1307,"height":743,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/workshop-Madrid-Groupe2-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/","url":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/","name":"ThermEcoWat franchit une \u00e9tape cl\u00e9 \u00e0 Madrid : les sites pilotes pr\u00e9sentent leurs premiers plans d\u2019action pour l\u2019adaptation - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/#primaryimage"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/#primaryimage"},"thumbnailUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/workshop-Madrid-Groupe2-1.jpeg","datePublished":"2026-06-09T12:33:12+00:00","dateModified":"2026-06-09T13:55:17+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/#primaryimage","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/workshop-Madrid-Groupe2-1.jpeg","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/06\/workshop-Madrid-Groupe2-1.jpeg","width":1307,"height":743,"caption":"ThermEcoWat Workshop in Madrid"},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/fr\/noticia-proyecto\/thermecowat-alcanza-un-hito-clave-en-madrid-los-sitios-piloto-presentan-sus-primeros-planes-de-accion-de-adaptacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"ThermEcoWat franchit une \u00e9tape cl\u00e9 \u00e0 Madrid : les sites pilotes pr\u00e9sentent leurs premiers plans d\u2019action pour l\u2019adaptation"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/fr\/#website","url":"https:\/\/interreg-sudoe.eu\/fr\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/noticia-proyecto\/68373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/noticia-proyecto"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/types\/noticia-proyecto"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/users\/6514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media\/68301"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media?parent=68373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}