{"id":49937,"date":"2026-07-20T13:46:54","date_gmt":"2026-07-20T11:46:54","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/piloto-proyecto-27\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\/"},"modified":"2026-07-20T13:46:54","modified_gmt":"2026-07-20T11:46:54","slug":"desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate","status":"publish","type":"piloto-proyecto-27","link":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\/","title":{"rendered":"Desarrollo, demostraci\u00f3n y evaluaci\u00f3n de BIPMS para el cultivo del tomate"},"content":{"rendered":"<p>Esta actividad piloto ser\u00e1 desarrollada por los socios COTHN y TECNOVA para la implantaci\u00f3n del BIPMS en el cultivo del tomate de acuerdo con el marco com\u00fan de experimentaci\u00f3n, seguimiento y evaluaci\u00f3n definido dentro del CAP bajo la coordinaci\u00f3n de TECNOVA.    Trabajar\u00e1n juntos al menos en el \u00e1caro responsable de la mancha bronceada (Aculops lycopersici). El objetivo ser\u00e1 evaluar individual y conjuntamente (en diferentes combinaciones) el uso de un bioestimulante microbiol\u00f3gico, un bioestimulante formulado con quitosano y un insecto depredador.    Cada LL desarrollar\u00e1 su propia estrategia adaptada al contexto local, para este patosistema com\u00fan, con el fin de proponer soluciones compartidas que puedan transferirse a otros territorios con contextos similares.     Podr\u00e1n estudiarse otros patosistemas en funci\u00f3n de las necesidades de cada LL. Los protocolos se elaborar\u00e1n conjuntamente: dise\u00f1o experimental (campo abierto o experimental simulando condiciones reales, tama\u00f1o de parcela, etc.), tratamiento (BIPMS, convencional, combinaci\u00f3n de ambos) y evaluaci\u00f3n (criterios EPPO, frecuencia, etc.) Los resultados se evaluar\u00e1n al final del 1er a\u00f1o para poder adaptar los protocolos del segundo a\u00f1o si fuera necesario. Se organizar\u00e1   una jornada de demostraci\u00f3n para al menos agricultores y empresas que desarrollen biosoluciones en cada LL para cada temporada experimental. Estas jornadas podr\u00e1n estar abiertas a otros actores en funci\u00f3n de los objetivos y actores implicados en cada LL.      Las soluciones ensayadas, evaluadas y demostradas conducir\u00e1n a la validaci\u00f3n de estrategias de lucha integrada contra las plagas y enfermedades del tomate mediante biosoluciones. Se difundir\u00e1n dentro de los LL y m\u00e1s ampliamente entre los agricultores, las PYME y las organizaciones intermediarias de apoyo (cooperativas, centros tecnol\u00f3gicos, etc.) para su aplicaci\u00f3n por otros actores y regiones del SUDOE.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta actividad piloto ser\u00e1 desarrollada por los socios COTHN y TECNOVA para la implantaci\u00f3n del BIPMS en el cultivo del tomate de acuerdo con el marco com\u00fan de experimentaci\u00f3n, seguimiento y evaluaci\u00f3n definido dentro del CAP bajo la coordinaci\u00f3n de TECNOVA. Trabajar\u00e1n juntos al menos en el \u00e1caro responsable de la mancha bronceada (Aculops lycopersici). [&hellip;]<\/p>\n","protected":false},"author":6690,"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"convocatoria-proyecto-27":[3219],"estado-proyecto-27":[3234],"objetivo-especifico-proyecto-27":[3892],"pais-proyecto-27":[],"periodo":[3551],"prioridad-proyecto-27":[3209],"publico-objetivo":[],"region-proyecto-27":[],"tematica-proyecto-27":[],"class_list":["post-49937","piloto-proyecto-27","type-piloto-proyecto-27","status-publish","hentry","convocatoria-proyecto-27-2a-convocatoria","estado-proyecto-27-en-curso","objetivo-especifico-proyecto-27-2-4-favorecer-la-adaptacion-al-cambio-climatico-y-la-prevencion-del-riesgo-de-catastrofes-asi-como-la-resiliencia-teniendo-en-cuenta-los-enfoques-basados-en-los-ecosistemas","periodo-2021-2027","prioridad-proyecto-27-1-preservar-el-capital-natural-y-reforzar-la-adaptacion-al-cambio-climatico-en-el-sudoe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desarrollo, demostraci\u00f3n y evaluaci\u00f3n de BIPMS para el cultivo del tomate - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desarrollo, demostraci\u00f3n y evaluaci\u00f3n de BIPMS para el cultivo del tomate - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"Esta actividad piloto ser\u00e1 desarrollada por los socios COTHN y TECNOVA para la implantaci\u00f3n del BIPMS en el cultivo del tomate de acuerdo con el marco com\u00fan de experimentaci\u00f3n, seguimiento y evaluaci\u00f3n definido dentro del CAP bajo la coordinaci\u00f3n de TECNOVA. Trabajar\u00e1n juntos al menos en el \u00e1caro responsable de la mancha bronceada (Aculops lycopersici). [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\\\/\",\"name\":\"Desarrollo, demostraci\u00f3n y evaluaci\u00f3n de BIPMS para el cultivo del tomate - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\"},\"datePublished\":\"2026-07-20T11:46:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desarrollo, demostraci\u00f3n y evaluaci\u00f3n de BIPMS para el cultivo del tomate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desarrollo, demostraci\u00f3n y evaluaci\u00f3n de BIPMS para el cultivo del tomate - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\/","og_locale":"fr_FR","og_type":"article","og_title":"Desarrollo, demostraci\u00f3n y evaluaci\u00f3n de BIPMS para el cultivo del tomate - Interreg Sudoe","og_description":"Esta actividad piloto ser\u00e1 desarrollada por los socios COTHN y TECNOVA para la implantaci\u00f3n del BIPMS en el cultivo del tomate de acuerdo con el marco com\u00fan de experimentaci\u00f3n, seguimiento y evaluaci\u00f3n definido dentro del CAP bajo la coordinaci\u00f3n de TECNOVA. Trabajar\u00e1n juntos al menos en el \u00e1caro responsable de la mancha bronceada (Aculops lycopersici). [&hellip;]","og_url":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","og_image":[{"width":344,"height":147,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\/","url":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\/","name":"Desarrollo, demostraci\u00f3n y evaluaci\u00f3n de BIPMS para el cultivo del tomate - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#website"},"datePublished":"2026-07-20T11:46:54+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/desarrollo-demostracion-y-evaluacion-de-bipms-para-el-cultivo-del-tomate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Desarrollo, demostraci\u00f3n y evaluaci\u00f3n de BIPMS para el cultivo del tomate"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/fr\/#website","url":"https:\/\/interreg-sudoe.eu\/fr\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/piloto-proyecto-27\/49937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/piloto-proyecto-27"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/types\/piloto-proyecto-27"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/users\/6690"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media?parent=49937"}],"wp:term":[{"taxonomy":"convocatoria-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/convocatoria-proyecto-27?post=49937"},{"taxonomy":"estado-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/estado-proyecto-27?post=49937"},{"taxonomy":"objetivo-especifico-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/objetivo-especifico-proyecto-27?post=49937"},{"taxonomy":"pais-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/pais-proyecto-27?post=49937"},{"taxonomy":"periodo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/periodo?post=49937"},{"taxonomy":"prioridad-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/prioridad-proyecto-27?post=49937"},{"taxonomy":"publico-objetivo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/publico-objetivo?post=49937"},{"taxonomy":"region-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/region-proyecto-27?post=49937"},{"taxonomy":"tematica-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/tematica-proyecto-27?post=49937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}