{"id":49944,"date":"2026-07-20T13:43:28","date_gmt":"2026-07-20T11:43:28","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/piloto-proyecto-27\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\/"},"modified":"2026-07-20T13:43:28","modified_gmt":"2026-07-20T11:43:28","slug":"ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo","status":"publish","type":"piloto-proyecto-27","link":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\/","title":{"rendered":"Ensayos de enmiendas de biocarb\u00f3n + compost en 3 zonas objetivo"},"content":{"rendered":"<p>En este grupo de trabajo, se llevar\u00e1 a cabo un experimento conjunto en las tres regiones del proyecto (Occitania, Alentejo, Galicia), en tres sitios por regi\u00f3n. Adem\u00e1s de estos ensayos de campo, la Universidad de Vigo tambi\u00e9n llevar\u00e1 a cabo ensayos de laboratorio, con el fin de probar una gama m\u00e1s amplia de suelos t\u00edpicos de las regiones del proyecto. El objetivo ser\u00e1 analizar los beneficios de las enmiendas de biocarb\u00f3n + compost en el suelo (fertilidad, biodiversidad, almacenamiento de carbono, capacidad de retenci\u00f3n de agua) y en la capacidad de la vid para ser m\u00e1s resistente a los riesgos clim\u00e1ticos, manteniendo el nivel requerido de productividad y calidad de la uva, y en condiciones econ\u00f3micamente aceptables para los viticultores. Gracias a estos experimentos conjuntos realizados en los tres pa\u00edses, ser\u00e1 posible emitir recomendaciones sobre enmiendas adaptadas a los diferentes tipos de suelo y clima que se dan en la regi\u00f3n SUDOE. Los resultados de los experimentos se completar\u00e1n con una revisi\u00f3n bibliogr\u00e1fica que permitir\u00e1 elaborar una gu\u00eda t\u00e9cnica de enmiendas del suelo a base de biocarb\u00f3n, la cual ser\u00e1 destinada a los viticultores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este grupo de trabajo, se llevar\u00e1 a cabo un experimento conjunto en las tres regiones del proyecto (Occitania, Alentejo, Galicia), en tres sitios por regi\u00f3n. Adem\u00e1s de estos ensayos de campo, la Universidad de Vigo tambi\u00e9n llevar\u00e1 a cabo ensayos de laboratorio, con el fin de probar una gama m\u00e1s amplia de suelos t\u00edpicos [&hellip;]<\/p>\n","protected":false},"author":6659,"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"convocatoria-proyecto-27":[3219],"estado-proyecto-27":[3234],"objetivo-especifico-proyecto-27":[3892],"pais-proyecto-27":[],"periodo":[3551],"prioridad-proyecto-27":[3209],"publico-objetivo":[],"region-proyecto-27":[],"tematica-proyecto-27":[],"class_list":["post-49944","piloto-proyecto-27","type-piloto-proyecto-27","status-publish","hentry","convocatoria-proyecto-27-2a-convocatoria","estado-proyecto-27-en-curso","objetivo-especifico-proyecto-27-2-4-favorecer-la-adaptacion-al-cambio-climatico-y-la-prevencion-del-riesgo-de-catastrofes-asi-como-la-resiliencia-teniendo-en-cuenta-los-enfoques-basados-en-los-ecosistemas","periodo-2021-2027","prioridad-proyecto-27-1-preservar-el-capital-natural-y-reforzar-la-adaptacion-al-cambio-climatico-en-el-sudoe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ensayos de enmiendas de biocarb\u00f3n + compost en 3 zonas objetivo - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ensayos de enmiendas de biocarb\u00f3n + compost en 3 zonas objetivo - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"En este grupo de trabajo, se llevar\u00e1 a cabo un experimento conjunto en las tres regiones del proyecto (Occitania, Alentejo, Galicia), en tres sitios por regi\u00f3n. Adem\u00e1s de estos ensayos de campo, la Universidad de Vigo tambi\u00e9n llevar\u00e1 a cabo ensayos de laboratorio, con el fin de probar una gama m\u00e1s amplia de suelos t\u00edpicos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\\\/\",\"name\":\"Ensayos de enmiendas de biocarb\u00f3n + compost en 3 zonas objetivo - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\"},\"datePublished\":\"2026-07-20T11:43:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ensayos de enmiendas de biocarb\u00f3n + compost en 3 zonas objetivo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ensayos de enmiendas de biocarb\u00f3n + compost en 3 zonas objetivo - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\/","og_locale":"fr_FR","og_type":"article","og_title":"Ensayos de enmiendas de biocarb\u00f3n + compost en 3 zonas objetivo - Interreg Sudoe","og_description":"En este grupo de trabajo, se llevar\u00e1 a cabo un experimento conjunto en las tres regiones del proyecto (Occitania, Alentejo, Galicia), en tres sitios por regi\u00f3n. Adem\u00e1s de estos ensayos de campo, la Universidad de Vigo tambi\u00e9n llevar\u00e1 a cabo ensayos de laboratorio, con el fin de probar una gama m\u00e1s amplia de suelos t\u00edpicos [&hellip;]","og_url":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","og_image":[{"width":344,"height":147,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\/","url":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\/","name":"Ensayos de enmiendas de biocarb\u00f3n + compost en 3 zonas objetivo - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#website"},"datePublished":"2026-07-20T11:43:28+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/ensayos-de-enmiendas-de-biocarbon-compost-en-3-zonas-objetivo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"Ensayos de enmiendas de biocarb\u00f3n + compost en 3 zonas objetivo"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/fr\/#website","url":"https:\/\/interreg-sudoe.eu\/fr\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/piloto-proyecto-27\/49944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/piloto-proyecto-27"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/types\/piloto-proyecto-27"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/users\/6659"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media?parent=49944"}],"wp:term":[{"taxonomy":"convocatoria-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/convocatoria-proyecto-27?post=49944"},{"taxonomy":"estado-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/estado-proyecto-27?post=49944"},{"taxonomy":"objetivo-especifico-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/objetivo-especifico-proyecto-27?post=49944"},{"taxonomy":"pais-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/pais-proyecto-27?post=49944"},{"taxonomy":"periodo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/periodo?post=49944"},{"taxonomy":"prioridad-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/prioridad-proyecto-27?post=49944"},{"taxonomy":"publico-objetivo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/publico-objetivo?post=49944"},{"taxonomy":"region-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/region-proyecto-27?post=49944"},{"taxonomy":"tematica-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/tematica-proyecto-27?post=49944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}