{"id":50056,"date":"2026-07-20T14:04:24","date_gmt":"2026-07-20T12:04:24","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/?post_type=piloto-proyecto-27&#038;p=50056"},"modified":"2026-07-20T14:04:24","modified_gmt":"2026-07-20T12:04:24","slug":"developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so","status":"publish","type":"piloto-proyecto-27","link":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\/","title":{"rendered":"D\u00e9veloppement d\u0092une plateforme num\u00e9rique pour am\u00e9liorer la litt\u00e9ratie et les connaissances en SO"},"content":{"rendered":"<p>Dans les 6 territoires pilotes : 1 territoire au Portugal (Alter do Ch\u00e3o), 2 en France (communaut\u00e9 de communes Larzac et Vall\u00e9es en Aveyron et Communaut\u00e9 de Communes du pays d\u0092Olmes en Ari\u00e8ge) et 3 en Espagnes (r\u00e9gion de Murcie, R\u00e9gion de Valence et Andalousie), des interventions seront men\u00e9es pour am\u00e9liorer la litt\u00e9ratie en sant\u00e9 orale des populations et augmenter les connaissances et comp\u00e9tences en sant\u00e9 orale des professionnels de sant\u00e9 et ceux en contact avec les populations. Pour cela, nous d\u00e9velopperons des contenus num\u00e9riques (outils de promotion de la sant\u00e9 comme des vid\u00e9os, des affiches et des campagnes de SMS) mais \u00e9galement nous cr\u00e9erons une offre de formation num\u00e9rique pour que les professionnels puissent se former \u00e0 la sant\u00e9 orale \u00e0 distance. Ces deux types de contenus seront regroup\u00e9s sur une m\u00eame plateforme afin que l\u0092information soit la plus simple possible \u00e0 trouver. Les contenus de promotion de la sant\u00e9 orale seront \u00e9galement directement utilis\u00e9s par les professionnels des territoires et les parties prenantes qui d\u00e9veloppent les programmes de pr\u00e9vention. Cette plateforme regroupera donc une biblioth\u00e8que de contenus et une formation en ligne accessibles \u00e0 tous et adapt\u00e9s aux publics cibles. Nous \u00e9valuerons la litt\u00e9ratie en sant\u00e9 orale de la population au d\u00e9but et \u00e0 la fin du projet et de m\u00eame pour le niveau de connaissance des professionnels. Nous pourrons donc savoir l\u0092impact qu\u0092auront eu ces outils. De plus, nous \u00e9valuerons l\u0092adh\u00e9sion et l\u0092usage de ces outils pour les rendre les plus facilement utilisables possible.   Dans le cadre du GT 3 nous souhaitons \u00e9galement travailler sur l&rsquo;int\u00e9gration de cette offre de formation dans le cadre de la formation initiale dans les facult\u00e9s et \u00e9coles de la zone SUDOE. Ainsi, la sant\u00e9 orale sera mieux connus de tous les professionnels de sant\u00e9 et pourra \u00eatre mieux prise en charge.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans les 6 territoires pilotes : 1 territoire au Portugal (Alter do Ch\u00e3o), 2 en France (communaut\u00e9 de communes Larzac et Vall\u00e9es en Aveyron et Communaut\u00e9 de Communes du pays d\u0092Olmes en Ari\u00e8ge) et 3 en Espagnes (r\u00e9gion de Murcie, R\u00e9gion de Valence et Andalousie), des interventions seront men\u00e9es pour am\u00e9liorer la litt\u00e9ratie en sant\u00e9 [&hellip;]<\/p>\n","protected":false},"author":6683,"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"convocatoria-proyecto-27":[3310],"estado-proyecto-27":[3363],"objetivo-especifico-proyecto-27":[3288],"pais-proyecto-27":[],"periodo":[3556],"prioridad-proyecto-27":[3272],"publico-objetivo":[],"region-proyecto-27":[],"tematica-proyecto-27":[],"class_list":["post-50056","piloto-proyecto-27","type-piloto-proyecto-27","status-publish","hentry","convocatoria-proyecto-27-2eme-appel-a-projets","estado-proyecto-27-en-cours","objetivo-especifico-proyecto-27-os-4-5-acces-aux-soins-systemes-de-sante","periodo-2021-2027-fr","prioridad-proyecto-27-3-promouvoir-la-cohesion-sociale-et-lequilibre-territorial-et-demographique-du-sudoe-a-travers-linnovation-sociale-la-valorisation-du-patrimoine-et-les-services"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9veloppement d\u0092une plateforme num\u00e9rique pour am\u00e9liorer la litt\u00e9ratie et les connaissances en SO - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9veloppement d\u0092une plateforme num\u00e9rique pour am\u00e9liorer la litt\u00e9ratie et les connaissances en SO - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"Dans les 6 territoires pilotes : 1 territoire au Portugal (Alter do Ch\u00e3o), 2 en France (communaut\u00e9 de communes Larzac et Vall\u00e9es en Aveyron et Communaut\u00e9 de Communes du pays d\u0092Olmes en Ari\u00e8ge) et 3 en Espagnes (r\u00e9gion de Murcie, R\u00e9gion de Valence et Andalousie), des interventions seront men\u00e9es pour am\u00e9liorer la litt\u00e9ratie en sant\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\\\/\",\"name\":\"D\u00e9veloppement d\u0092une plateforme num\u00e9rique pour am\u00e9liorer la litt\u00e9ratie et les connaissances en SO - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\"},\"datePublished\":\"2026-07-20T12:04:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/piloto-proyecto-27\\\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9veloppement d\u0092une plateforme num\u00e9rique pour am\u00e9liorer la litt\u00e9ratie et les connaissances en SO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9veloppement d\u0092une plateforme num\u00e9rique pour am\u00e9liorer la litt\u00e9ratie et les connaissances en SO - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9veloppement d\u0092une plateforme num\u00e9rique pour am\u00e9liorer la litt\u00e9ratie et les connaissances en SO - Interreg Sudoe","og_description":"Dans les 6 territoires pilotes : 1 territoire au Portugal (Alter do Ch\u00e3o), 2 en France (communaut\u00e9 de communes Larzac et Vall\u00e9es en Aveyron et Communaut\u00e9 de Communes du pays d\u0092Olmes en Ari\u00e8ge) et 3 en Espagnes (r\u00e9gion de Murcie, R\u00e9gion de Valence et Andalousie), des interventions seront men\u00e9es pour am\u00e9liorer la litt\u00e9ratie en sant\u00e9 [&hellip;]","og_url":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","og_image":[{"width":344,"height":147,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\/","url":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\/","name":"D\u00e9veloppement d\u0092une plateforme num\u00e9rique pour am\u00e9liorer la litt\u00e9ratie et les connaissances en SO - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#website"},"datePublished":"2026-07-20T12:04:24+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/fr\/piloto-proyecto-27\/developpement-d%c2%92une-plateforme-numerique-pour-ameliorer-la-litteratie-et-les-connaissances-en-so\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9veloppement d\u0092une plateforme num\u00e9rique pour am\u00e9liorer la litt\u00e9ratie et les connaissances en SO"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/fr\/#website","url":"https:\/\/interreg-sudoe.eu\/fr\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/piloto-proyecto-27\/50056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/piloto-proyecto-27"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/types\/piloto-proyecto-27"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/users\/6683"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media?parent=50056"}],"wp:term":[{"taxonomy":"convocatoria-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/convocatoria-proyecto-27?post=50056"},{"taxonomy":"estado-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/estado-proyecto-27?post=50056"},{"taxonomy":"objetivo-especifico-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/objetivo-especifico-proyecto-27?post=50056"},{"taxonomy":"pais-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/pais-proyecto-27?post=50056"},{"taxonomy":"periodo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/periodo?post=50056"},{"taxonomy":"prioridad-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/prioridad-proyecto-27?post=50056"},{"taxonomy":"publico-objetivo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/publico-objetivo?post=50056"},{"taxonomy":"region-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/region-proyecto-27?post=50056"},{"taxonomy":"tematica-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/tematica-proyecto-27?post=50056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}