{"id":50370,"date":"2026-07-20T13:27:40","date_gmt":"2026-07-20T11:27:40","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/?post_type=resultado-proyecto-2&#038;p=50370"},"modified":"2026-07-20T13:27:42","modified_gmt":"2026-07-20T11:27:42","slug":"adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs","status":"publish","type":"resultado-proyecto-2","link":"https:\/\/interreg-sudoe.eu\/fr\/resultado-proyecto-2\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\/","title":{"rendered":"ADOPTION ET MISE EN \u008cUVRE CONJOINTE de la \u00ab Strat\u00e9gie \u00bb et du \u00ab Plan d&rsquo;action \u00bb des \u00ab RS-Labs \u00bb."},"content":{"rendered":"<p>ADOPTION ET MISE EN \u008cUVRE d&rsquo;une \u00ab Strat\u00e9gie \u00bb et d&rsquo;un \u00ab Plan d&rsquo;action \u00bb communs (1 unit\u00e9\/kit)  Il s&rsquo;agit de l&rsquo;adoption et de la mise en \u009cuvre d&rsquo;une \u00ab Strat\u00e9gie \u00bb commune + d&rsquo;un \u00ab Plan d&rsquo;action \u00bb commun \u00e0 d\u00e9velopper de mani\u00e8re homog\u00e8ne sur le territoire du SUDOE dans les \u00ab Laboratoires d&rsquo;innovation sociale et num\u00e9rique dans les environnements ruraux d\u00e9peupl\u00e9s (RS-Labs) \u00bb.   De cette mani\u00e8re, il sera possible de travailler \u00e0 l&rsquo;avenir sur l&rsquo;ensemble du territoire SUDOE, avec un protocole commun, en renfor\u00e7ant le travail en r\u00e9seau et le retour d&rsquo;information entre les territoires, et en \u00e9vitant que chaque territoire ne d\u00e9finisse seul des mod\u00e8les qui ne sont alors valables que dans des zones tr\u00e8s restreintes. Si nous parlons tous le m\u00eame langage et avons des proc\u00e9dures communes, il sera plus facile de travailler en r\u00e9seau, de capitaliser et d&rsquo;exploiter les r\u00e9sultats obtenus dans d&rsquo;autres territoires et de maximiser les ressources limit\u00e9es qui sont g\u00e9n\u00e9ralement disponibles pour d\u00e9velopper des politiques sociales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ADOPTION ET MISE EN \u008cUVRE d&rsquo;une \u00ab Strat\u00e9gie \u00bb et d&rsquo;un \u00ab Plan d&rsquo;action \u00bb communs (1 unit\u00e9\/kit) Il s&rsquo;agit de l&rsquo;adoption et de la mise en \u009cuvre d&rsquo;une \u00ab Strat\u00e9gie \u00bb commune + d&rsquo;un \u00ab Plan d&rsquo;action \u00bb commun \u00e0 d\u00e9velopper de mani\u00e8re homog\u00e8ne sur le territoire du SUDOE dans les \u00ab Laboratoires d&rsquo;innovation [&hellip;]<\/p>\n","protected":false},"author":6663,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"convocatoria-proyecto-27":[3310],"estado-proyecto-27":[3363],"objetivo-especifico-proyecto-27":[3287],"periodo":[3556],"prioridad-proyecto-27":[3272],"publico-objetivo":[],"tematica-proyecto-27":[],"tipo-resultado":[3939],"class_list":["post-50370","resultado-proyecto-2","type-resultado-proyecto-2","status-publish","hentry","convocatoria-proyecto-27-2eme-appel-a-projets","estado-proyecto-27-en-cours","objetivo-especifico-proyecto-27-os-4-1-marches-du-travail-developpement-des-infrastructures-economie-sociale","periodo-2021-2027-fr","prioridad-proyecto-27-3-promouvoir-la-cohesion-sociale-et-lequilibre-territorial-et-demographique-du-sudoe-a-travers-linnovation-sociale-la-valorisation-du-patrimoine-et-les-services","tipo-resultado-strategie-plan-daction"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ADOPTION ET MISE EN \u008cUVRE CONJOINTE de la \u00ab Strat\u00e9gie \u00bb et du \u00ab Plan d&#039;action \u00bb des \u00ab RS-Labs \u00bb. - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/fr\/resultado-proyecto-2\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ADOPTION ET MISE EN \u008cUVRE CONJOINTE de la \u00ab Strat\u00e9gie \u00bb et du \u00ab Plan d&#039;action \u00bb des \u00ab RS-Labs \u00bb. - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"ADOPTION ET MISE EN \u008cUVRE d&rsquo;une \u00ab Strat\u00e9gie \u00bb et d&rsquo;un \u00ab Plan d&rsquo;action \u00bb communs (1 unit\u00e9\/kit) Il s&rsquo;agit de l&rsquo;adoption et de la mise en \u009cuvre d&rsquo;une \u00ab Strat\u00e9gie \u00bb commune + d&rsquo;un \u00ab Plan d&rsquo;action \u00bb commun \u00e0 d\u00e9velopper de mani\u00e8re homog\u00e8ne sur le territoire du SUDOE dans les \u00ab Laboratoires d&rsquo;innovation [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/fr\/resultado-proyecto-2\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-20T11:27:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/resultado-proyecto-2\\\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/resultado-proyecto-2\\\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\\\/\",\"name\":\"ADOPTION ET MISE EN \u008cUVRE CONJOINTE de la \u00ab Strat\u00e9gie \u00bb et du \u00ab Plan d'action \u00bb des \u00ab RS-Labs \u00bb. - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\"},\"datePublished\":\"2026-07-20T11:27:40+00:00\",\"dateModified\":\"2026-07-20T11:27:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/resultado-proyecto-2\\\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/resultado-proyecto-2\\\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/resultado-proyecto-2\\\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ADOPTION ET MISE EN \u008cUVRE CONJOINTE de la \u00ab Strat\u00e9gie \u00bb et du \u00ab Plan d&#8217;action \u00bb des \u00ab RS-Labs \u00bb.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ADOPTION ET MISE EN \u008cUVRE CONJOINTE de la \u00ab Strat\u00e9gie \u00bb et du \u00ab Plan d'action \u00bb des \u00ab RS-Labs \u00bb. - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/fr\/resultado-proyecto-2\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\/","og_locale":"fr_FR","og_type":"article","og_title":"ADOPTION ET MISE EN \u008cUVRE CONJOINTE de la \u00ab Strat\u00e9gie \u00bb et du \u00ab Plan d'action \u00bb des \u00ab RS-Labs \u00bb. - Interreg Sudoe","og_description":"ADOPTION ET MISE EN \u008cUVRE d&rsquo;une \u00ab Strat\u00e9gie \u00bb et d&rsquo;un \u00ab Plan d&rsquo;action \u00bb communs (1 unit\u00e9\/kit) Il s&rsquo;agit de l&rsquo;adoption et de la mise en \u009cuvre d&rsquo;une \u00ab Strat\u00e9gie \u00bb commune + d&rsquo;un \u00ab Plan d&rsquo;action \u00bb commun \u00e0 d\u00e9velopper de mani\u00e8re homog\u00e8ne sur le territoire du SUDOE dans les \u00ab Laboratoires d&rsquo;innovation [&hellip;]","og_url":"https:\/\/interreg-sudoe.eu\/fr\/resultado-proyecto-2\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","article_modified_time":"2026-07-20T11:27:42+00:00","og_image":[{"width":344,"height":147,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/fr\/resultado-proyecto-2\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\/","url":"https:\/\/interreg-sudoe.eu\/fr\/resultado-proyecto-2\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\/","name":"ADOPTION ET MISE EN \u008cUVRE CONJOINTE de la \u00ab Strat\u00e9gie \u00bb et du \u00ab Plan d'action \u00bb des \u00ab RS-Labs \u00bb. - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#website"},"datePublished":"2026-07-20T11:27:40+00:00","dateModified":"2026-07-20T11:27:42+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/resultado-proyecto-2\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/fr\/resultado-proyecto-2\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/fr\/resultado-proyecto-2\/adoption-et-mise-en-%c2%8cuvre-conjointe-de-la-strategie-et-du-plan-daction-des-rs-labs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/fr\/"},{"@type":"ListItem","position":2,"name":"ADOPTION ET MISE EN \u008cUVRE CONJOINTE de la \u00ab Strat\u00e9gie \u00bb et du \u00ab Plan d&#8217;action \u00bb des \u00ab RS-Labs \u00bb."}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/fr\/#website","url":"https:\/\/interreg-sudoe.eu\/fr\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/fr\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/resultado-proyecto-2\/50370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/resultado-proyecto-2"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/types\/resultado-proyecto-2"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/users\/6663"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/media?parent=50370"}],"wp:term":[{"taxonomy":"convocatoria-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/convocatoria-proyecto-27?post=50370"},{"taxonomy":"estado-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/estado-proyecto-27?post=50370"},{"taxonomy":"objetivo-especifico-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/objetivo-especifico-proyecto-27?post=50370"},{"taxonomy":"periodo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/periodo?post=50370"},{"taxonomy":"prioridad-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/prioridad-proyecto-27?post=50370"},{"taxonomy":"publico-objetivo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/publico-objetivo?post=50370"},{"taxonomy":"tematica-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/tematica-proyecto-27?post=50370"},{"taxonomy":"tipo-resultado","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/fr\/wp-json\/wp\/v2\/tipo-resultado?post=50370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}