{"id":47505,"date":"2025-05-30T12:48:28","date_gmt":"2025-05-30T10:48:28","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/?post_type=noticia-proyecto&#038;p=47505"},"modified":"2025-05-30T12:48:36","modified_gmt":"2025-05-30T10:48:36","slug":"cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi","status":"publish","type":"noticia-proyecto","link":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/","title":{"rendered":"CIDETEC visita Don Bosco para impulsionar o projeto RESINSURF e promover solu\u00e7\u00f5es livres de Cr(VI)"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>A <a href=\"https:\/\/surfaceengineering.cidetec.es\/\">CIDETEC Surface\u00a0Engineering<\/a> visitou recentemente o <a href=\"https:\/\/www.donbosco.eus\/es\/\">Don Bosco<\/a>no \u00e2mbito do projeto <a href=\"https:\/\/interreg-sudoe.eu\/en\/proyecto-interreg\/resinsurf\/\">RESINSURF<\/a>, uma iniciativa destinada a oferecer alternativas sustent\u00e1veis e livres de cromo hexavalente (Cr(VI)) para a ind\u00fastria de tratamento de superf\u00edcies. A visita incluiu um tour pelas instala\u00e7\u00f5es do <a href=\"https:\/\/www.donbosco.eus\/es\/\">Don Bosco<\/a> e discuss\u00f5es focadas no desenvolvimento de atividades de forma\u00e7\u00e3o e capacita\u00e7\u00e3o, aproximando profissionais atuais e futuros de tecnologias de tratamento de superf\u00edcies mais seguras e ecol\u00f3gicas.<br \/>\nO <a href=\"https:\/\/www.donbosco.eus\/es\/\">Don Bosco<\/a>, parceiro associado do <a href=\"https:\/\/interreg-sudoe.eu\/en\/proyecto-interreg\/resinsurf\/\">RESINSURF<\/a>, desempenha um papel fundamental nas atividades educativas e de divulga\u00e7\u00e3o do projeto. Com sua s\u00f3lida experi\u00eancia em forma\u00e7\u00e3o t\u00e9cnica e profissional, o <a href=\"https:\/\/www.donbosco.eus\/es\/\">Don Bosco<\/a> apoia o projeto colaborando no desenvolvimento de materiais e ambientes de forma\u00e7\u00e3o adequados. Essas atividades s\u00e3o centrais para a estrat\u00e9gia do <a href=\"https:\/\/interreg-sudoe.eu\/en\/proyecto-interreg\/resinsurf\/\">RESINSURF<\/a> de aprimorar as compet\u00eancias da for\u00e7a de trabalho e facilitar a ado\u00e7\u00e3o de solu\u00e7\u00f5es livres de Cr(VI) em toda a regi\u00e3o SUDOE.<br \/>\nO projeto <a href=\"https:\/\/interreg-sudoe.eu\/en\/proyecto-interreg\/resinsurf\/\">RESINSURF<\/a>, coordenado pela <a href=\"https:\/\/surfaceengineering.cidetec.es\/\">CIDETEC Surface\u00a0Engineering<\/a> e cofinanciado pelo programa <a href=\"https:\/\/interreg-sudoe.eu\/pt-pt\/\">Interreg SUDOE<\/a>, prioriza a transfer\u00eancia de conhecimento e a forma\u00e7\u00e3o profissional como ferramentas essenciais para a transi\u00e7\u00e3o ecol\u00f3gica do setor. Ao envolver institui\u00e7\u00f5es como o <a href=\"https:\/\/www.donbosco.eus\/es\/\">Don Bosco<\/a>, o projeto garante que tanto profissionais da ind\u00fastria quanto estudantes estejam preparados para implementar processos inovadores e seguros de tratamento de superf\u00edcies, apoiando o emprego regional e o cumprimento das rigorosas normas europeias sobre subst\u00e2ncias perigosas.<br \/>\nEssa abordagem colaborativa n\u00e3o s\u00f3 acelera a ado\u00e7\u00e3o de tecnologias sustent\u00e1veis, mas tamb\u00e9m fortalece a conex\u00e3o entre educa\u00e7\u00e3o, pesquisa e ind\u00fastria, assegurando uma for\u00e7a de trabalho pronta para o futuro do setor de tratamento de superf\u00edcies.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A CIDETEC visitou o Don Bosco no \u00e2mbito do Projeto RESINSURF. A colabora\u00e7\u00e3o foca na forma\u00e7\u00e3o e capacita\u00e7\u00e3o para preparar profissionais atuais e futuros para a ado\u00e7\u00e3o de tecnologias de tratamento de superf\u00edcies mais seguras.<\/p>\n","protected":false},"author":4905,"featured_media":47497,"parent":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"class_list":["post-47505","noticia-proyecto","type-noticia-proyecto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CIDETEC visita Don Bosco para impulsionar o projeto RESINSURF e promover solu\u00e7\u00f5es livres de Cr(VI) - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CIDETEC visita Don Bosco para impulsionar o projeto RESINSURF e promover solu\u00e7\u00f5es livres de Cr(VI) - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"A CIDETEC visitou o Don Bosco no \u00e2mbito do Projeto RESINSURF. A colabora\u00e7\u00e3o foca na forma\u00e7\u00e3o e capacita\u00e7\u00e3o para preparar profissionais atuais e futuros para a ado\u00e7\u00e3o de tecnologias de tratamento de superf\u00edcies mais seguras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-30T10:48:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/05\/Foto-Grupo-e1748595670589.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"918\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\\\/\",\"name\":\"CIDETEC visita Don Bosco para impulsionar o projeto RESINSURF e promover solu\u00e7\u00f5es livres de Cr(VI) - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Foto-Grupo-e1748595670589.jpg\",\"datePublished\":\"2025-05-30T10:48:28+00:00\",\"dateModified\":\"2025-05-30T10:48:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Foto-Grupo-e1748595670589.jpg\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Foto-Grupo-e1748595670589.jpg\",\"width\":1000,\"height\":918},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CIDETEC visita Don Bosco para impulsionar o projeto RESINSURF e promover solu\u00e7\u00f5es livres de Cr(VI)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CIDETEC visita Don Bosco para impulsionar o projeto RESINSURF e promover solu\u00e7\u00f5es livres de Cr(VI) - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/","og_locale":"pt_PT","og_type":"article","og_title":"CIDETEC visita Don Bosco para impulsionar o projeto RESINSURF e promover solu\u00e7\u00f5es livres de Cr(VI) - Interreg Sudoe","og_description":"A CIDETEC visitou o Don Bosco no \u00e2mbito do Projeto RESINSURF. A colabora\u00e7\u00e3o foca na forma\u00e7\u00e3o e capacita\u00e7\u00e3o para preparar profissionais atuais e futuros para a ado\u00e7\u00e3o de tecnologias de tratamento de superf\u00edcies mais seguras.","og_url":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","article_modified_time":"2025-05-30T10:48:36+00:00","og_image":[{"width":1000,"height":918,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/05\/Foto-Grupo-e1748595670589.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/","name":"CIDETEC visita Don Bosco para impulsionar o projeto RESINSURF e promover solu\u00e7\u00f5es livres de Cr(VI) - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/#primaryimage"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/#primaryimage"},"thumbnailUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/05\/Foto-Grupo-e1748595670589.jpg","datePublished":"2025-05-30T10:48:28+00:00","dateModified":"2025-05-30T10:48:36+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/#primaryimage","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/05\/Foto-Grupo-e1748595670589.jpg","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2025\/05\/Foto-Grupo-e1748595670589.jpg","width":1000,"height":918},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/cidetec-visita-don-bosco-para-impulsionar-o-projeto-resinsurf-e-promover-solucoes-livres-de-crvi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"CIDETEC visita Don Bosco para impulsionar o projeto RESINSURF e promover solu\u00e7\u00f5es livres de Cr(VI)"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#website","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/noticia-proyecto\/47505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/noticia-proyecto"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/types\/noticia-proyecto"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/users\/4905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/media\/47497"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=47505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}