{"id":64960,"date":"2026-04-29T13:06:18","date_gmt":"2026-04-29T11:06:18","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/?post_type=noticia-proyecto&#038;p=64960"},"modified":"2026-04-30T11:53:11","modified_gmt":"2026-04-30T09:53:11","slug":"as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas","status":"publish","type":"noticia-proyecto","link":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/","title":{"rendered":"As a\u00e7\u00f5es-piloto desenvolvidas pela Regi\u00e3o de M\u00farcia no \u00e2mbito do projeto SocialForest, um exemplo de conserva\u00e7\u00e3o face ao desafio das altera\u00e7\u00f5es clim\u00e1ticas"},"content":{"rendered":"<p>Oferecer uma vis\u00e3o sobre a conserva\u00e7\u00e3o das florestas do Noroeste face ao desafio das altera\u00e7\u00f5es clim\u00e1ticas foi o eixo central da jornada t\u00e9cnica organizada esta ter\u00e7a-feira pela C\u00e1tedra de Ambiente, \u00c1gua e Energia UCAM\u2013Grupo Hozono Global, na qual esteve presente o projeto SocialForest, do programa Interreg Sudoe. Isto ocorreu atrav\u00e9s das duas a\u00e7\u00f5es-piloto que a CARM, parceiro coordenador do projeto, est\u00e1 a desenvolver em duas \u00e1reas florestais de M\u00farcia (<a href=\"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/la-region-de-murcia-convierte-sus-montes-en-laboratorio-climatico-con-dos-acciones-piloto-en-el-marco-de-socialforest\/\">Ceheg\u00edn e Moratalla<\/a>). Durante o encontro, foram abordados os desafios da gest\u00e3o das massas florestais e as oportunidades que se abrem no \u00e2mbito de uma economia sustent\u00e1vel.<\/p>\n<p>Com o t\u00edtulo <a href=\"https:\/\/eventos.ucam.edu\/152817\/detail\/gestion-forestal-la-conservacion-de-los-bosques-del-noroeste-ante-el-desafio-del-cambio-climatico.html\">\u00abGest\u00e3o florestal: a conserva\u00e7\u00e3o das florestas do Noroeste face ao desafio das altera\u00e7\u00f5es clim\u00e1ticas\u00bb<\/a>, a jornada reuniu representantes da administra\u00e7\u00e3o p\u00fablica, profissionais do setor e propriet\u00e1rios florestais. Em representa\u00e7\u00e3o da CARM, a secret\u00e1ria regional de Energia, Sustentabilidade e A\u00e7\u00e3o Clim\u00e1tica da Consejer\u00eda de Ambiente, Universidades, Investiga\u00e7\u00e3o e Mar Menor, Mar\u00eda Cruz Ferreira Costa, foi respons\u00e1vel pela abertura do encontro, e a engenheira florestal da Dire\u00e7\u00e3o-Geral do Patrim\u00f3nio Natural da CARM, Ana Mar\u00eda Atienza P\u00e9rez, apresentou as a\u00e7\u00f5es-piloto que est\u00e3o a ser desenvolvidas em M\u00farcia atrav\u00e9s do projeto SocialForest.<\/p>\n<p>Durante o encontro, foram abordados aspetos-chave relacionados com a conserva\u00e7\u00e3o dos espa\u00e7os florestais, com especial aten\u00e7\u00e3o \u00e0 adapta\u00e7\u00e3o das florestas \u00e0s novas condi\u00e7\u00f5es ambientais. Foram igualmente analisadas diferentes perspetivas sobre a gest\u00e3o florestal, incluindo a colabora\u00e7\u00e3o entre administra\u00e7\u00f5es p\u00fablicas e entidades privadas, o papel dos propriet\u00e1rios florestais e a aplica\u00e7\u00e3o de inova\u00e7\u00f5es t\u00e9cnicas e cient\u00edficas neste dom\u00ednio.<\/p>\n<p>O evento teve como objetivo oferecer uma vis\u00e3o atualizada e rigorosa da problem\u00e1tica do setor, promovendo a reflex\u00e3o e a troca de conhecimentos entre profissionais, t\u00e9cnicos e p\u00fablico interessado. Desta forma, contribui-se para melhorar a compreens\u00e3o dos desafios existentes e para divulgar boas pr\u00e1ticas orientadas para a conserva\u00e7\u00e3o e gest\u00e3o respons\u00e1vel dos recursos florestais.<\/p>\n<p><a href=\"https:\/\/www.instagram.com\/socialforest_sudoe\/?next=https%3A%2F%2Fwww.instagram.com%2Faccounts%2Fonetap%2F%3Fnext%3D%252F%26__coig_login%3D1\"><strong>Instagram<\/strong><\/a>\u00a0(@socialforest_sudoe)<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/profile.php?id=61577185415058\"><strong>Facebook<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/company\/social-forest-sudoe\/?viewAsMember=true\"><strong>Linkedin<\/strong><\/a><\/p>\n<p><strong><a href=\"https:\/\/www.canva.com\/design\/DAG5mIzJdBU\/NpA2us-IhXukEFVopVZMiA\/view?utm_content=DAG5mIzJdBU&amp;utm_campaign=designshare&amp;utm_medium=link2&amp;utm_source=uniquelinks&amp;utlId=h406e18384a\">Newsletter 2<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A CARM apresenta os desafios de gest\u00e3o florestal que enfrenta nas suas experi\u00eancias-piloto numa jornada t\u00e9cnica organizada pela C\u00e1tedra de Ambiente, \u00c1gua e Energia UCAM\u2013Grupo Hozono Global.<\/p>\n","protected":false},"author":6602,"featured_media":65180,"parent":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-64960","noticia-proyecto","type-noticia-proyecto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As a\u00e7\u00f5es-piloto desenvolvidas pela Regi\u00e3o de M\u00farcia no \u00e2mbito do projeto SocialForest, um exemplo de conserva\u00e7\u00e3o face ao desafio das altera\u00e7\u00f5es clim\u00e1ticas - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As a\u00e7\u00f5es-piloto desenvolvidas pela Regi\u00e3o de M\u00farcia no \u00e2mbito do projeto SocialForest, um exemplo de conserva\u00e7\u00e3o face ao desafio das altera\u00e7\u00f5es clim\u00e1ticas - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"A CARM apresenta os desafios de gest\u00e3o florestal que enfrenta nas suas experi\u00eancias-piloto numa jornada t\u00e9cnica organizada pela C\u00e1tedra de Ambiente, \u00c1gua e Energia UCAM\u2013Grupo Hozono Global.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T09:53:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/SF-Murcia-Caravaca-buena-e1777542669223.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1960\" \/>\n\t<meta property=\"og:image:height\" content=\"1046\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\\\/\",\"name\":\"As a\u00e7\u00f5es-piloto desenvolvidas pela Regi\u00e3o de M\u00farcia no \u00e2mbito do projeto SocialForest, um exemplo de conserva\u00e7\u00e3o face ao desafio das altera\u00e7\u00f5es clim\u00e1ticas - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/SF-Murcia-Caravaca-buena-e1777542669223.jpg\",\"datePublished\":\"2026-04-29T11:06:18+00:00\",\"dateModified\":\"2026-04-30T09:53:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/SF-Murcia-Caravaca-buena-e1777542669223.jpg\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/SF-Murcia-Caravaca-buena-e1777542669223.jpg\",\"width\":1960,\"height\":1046},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/noticia-proyecto\\\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As a\u00e7\u00f5es-piloto desenvolvidas pela Regi\u00e3o de M\u00farcia no \u00e2mbito do projeto SocialForest, um exemplo de conserva\u00e7\u00e3o face ao desafio das altera\u00e7\u00f5es clim\u00e1ticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As a\u00e7\u00f5es-piloto desenvolvidas pela Regi\u00e3o de M\u00farcia no \u00e2mbito do projeto SocialForest, um exemplo de conserva\u00e7\u00e3o face ao desafio das altera\u00e7\u00f5es clim\u00e1ticas - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/","og_locale":"pt_PT","og_type":"article","og_title":"As a\u00e7\u00f5es-piloto desenvolvidas pela Regi\u00e3o de M\u00farcia no \u00e2mbito do projeto SocialForest, um exemplo de conserva\u00e7\u00e3o face ao desafio das altera\u00e7\u00f5es clim\u00e1ticas - Interreg Sudoe","og_description":"A CARM apresenta os desafios de gest\u00e3o florestal que enfrenta nas suas experi\u00eancias-piloto numa jornada t\u00e9cnica organizada pela C\u00e1tedra de Ambiente, \u00c1gua e Energia UCAM\u2013Grupo Hozono Global.","og_url":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","article_modified_time":"2026-04-30T09:53:11+00:00","og_image":[{"width":1960,"height":1046,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/SF-Murcia-Caravaca-buena-e1777542669223.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/","name":"As a\u00e7\u00f5es-piloto desenvolvidas pela Regi\u00e3o de M\u00farcia no \u00e2mbito do projeto SocialForest, um exemplo de conserva\u00e7\u00e3o face ao desafio das altera\u00e7\u00f5es clim\u00e1ticas - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/#primaryimage"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/#primaryimage"},"thumbnailUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/SF-Murcia-Caravaca-buena-e1777542669223.jpg","datePublished":"2026-04-29T11:06:18+00:00","dateModified":"2026-04-30T09:53:11+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/#primaryimage","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/SF-Murcia-Caravaca-buena-e1777542669223.jpg","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2026\/04\/SF-Murcia-Caravaca-buena-e1777542669223.jpg","width":1960,"height":1046},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/noticia-proyecto\/as-acoes-piloto-desenvolvidas-pela-regiao-de-murcia-no-ambito-do-projeto-socialforest-um-exemplo-de-conservacao-face-ao-desafio-das-alteracoes-climaticas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"As a\u00e7\u00f5es-piloto desenvolvidas pela Regi\u00e3o de M\u00farcia no \u00e2mbito do projeto SocialForest, um exemplo de conserva\u00e7\u00e3o face ao desafio das altera\u00e7\u00f5es clim\u00e1ticas"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#website","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/noticia-proyecto\/64960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/noticia-proyecto"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/types\/noticia-proyecto"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/users\/6602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/media\/65180"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=64960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}