{"id":50166,"date":"2026-07-20T14:28:16","date_gmt":"2026-07-20T12:28:16","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/?post_type=piloto-proyecto-27&#038;p=50166"},"modified":"2026-07-20T14:28:20","modified_gmt":"2026-07-20T12:28:20","slug":"ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos","status":"publish","type":"piloto-proyecto-27","link":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\/","title":{"rendered":"Ensai-piloto das pr\u00e1ticas agroecol\u00f3gicas para a promo\u00e7\u00e3o de artr\u00f3podos"},"content":{"rendered":"<p>As pr\u00e1ticas agro-ecol\u00f3gicas previamente definidas e especificadas no GT1, bem como as poss\u00edveis medidas da PAC existentes para a promo\u00e7\u00e3o de artr\u00f3podes, ser\u00e3o testadas \u00e0 escala demonstrativa em diferentes territ\u00f3rios, culturas e tipos de sistemas de produ\u00e7\u00e3o, com o objetivo de obter uma metodologia robusta de promo\u00e7\u00e3o de artr\u00f3podes que possa ser replic\u00e1vel a outras culturas e contextos produtivos representativos do espa\u00e7o Sudoe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As pr\u00e1ticas agro-ecol\u00f3gicas previamente definidas e especificadas no GT1, bem como as poss\u00edveis medidas da PAC existentes para a promo\u00e7\u00e3o de artr\u00f3podes, ser\u00e3o testadas \u00e0 escala demonstrativa em diferentes territ\u00f3rios, culturas e tipos de sistemas de produ\u00e7\u00e3o, com o objetivo de obter uma metodologia robusta de promo\u00e7\u00e3o de artr\u00f3podes que possa ser replic\u00e1vel a outras [&hellip;]<\/p>\n","protected":false},"author":6673,"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"convocatoria-proyecto-27":[3312],"estado-proyecto-27":[3364],"objetivo-especifico-proyecto-27":[4080,3918,3295],"pais-proyecto-27":[],"periodo":[3557],"prioridad-proyecto-27":[3274],"publico-objetivo":[],"region-proyecto-27":[],"tematica-proyecto-27":[],"class_list":["post-50166","piloto-proyecto-27","type-piloto-proyecto-27","status-publish","hentry","convocatoria-proyecto-27-2a-convocatoria-pt-pt","estado-proyecto-27-em-curso","objetivo-especifico-proyecto-27-2-7-incrementar-la-proteccion-y-la-conservacion-de-la-naturaleza-la-biodiversidad-y-las-infraestructuras-verdes-tambien-en-las-zonas-urbanas-y-reducir-toda-forma-de-contaminacion","objetivo-especifico-proyecto-27-2-7-reforcar-a-protecao-e-preservacao-da-natureza-a-biodiversidade-e-as-infraestruturas-verdes-inclusive-nas-zonas-urbanas-e-reduzir-todas-as-formas-de-poluicao","objetivo-especifico-proyecto-27-oe-2-7-protecao-e-preservacao-da-natureza-biodiversidade-infraestruturas-verdes","periodo-2021-2027-pt-pt","prioridad-proyecto-27-1-preservar-o-capital-natural-e-reforcar-a-adaptacao-as-alteracoes-climaticas-no-sudoe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ensai-piloto das pr\u00e1ticas agroecol\u00f3gicas para a promo\u00e7\u00e3o de artr\u00f3podos - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ensai-piloto das pr\u00e1ticas agroecol\u00f3gicas para a promo\u00e7\u00e3o de artr\u00f3podos - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"As pr\u00e1ticas agro-ecol\u00f3gicas previamente definidas e especificadas no GT1, bem como as poss\u00edveis medidas da PAC existentes para a promo\u00e7\u00e3o de artr\u00f3podes, ser\u00e3o testadas \u00e0 escala demonstrativa em diferentes territ\u00f3rios, culturas e tipos de sistemas de produ\u00e7\u00e3o, com o objetivo de obter uma metodologia robusta de promo\u00e7\u00e3o de artr\u00f3podes que possa ser replic\u00e1vel a outras [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-20T12:28:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\\\/\",\"name\":\"Ensai-piloto das pr\u00e1ticas agroecol\u00f3gicas para a promo\u00e7\u00e3o de artr\u00f3podos - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#website\"},\"datePublished\":\"2026-07-20T12:28:16+00:00\",\"dateModified\":\"2026-07-20T12:28:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ensai-piloto das pr\u00e1ticas agroecol\u00f3gicas para a promo\u00e7\u00e3o de artr\u00f3podos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ensai-piloto das pr\u00e1ticas agroecol\u00f3gicas para a promo\u00e7\u00e3o de artr\u00f3podos - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\/","og_locale":"pt_PT","og_type":"article","og_title":"Ensai-piloto das pr\u00e1ticas agroecol\u00f3gicas para a promo\u00e7\u00e3o de artr\u00f3podos - Interreg Sudoe","og_description":"As pr\u00e1ticas agro-ecol\u00f3gicas previamente definidas e especificadas no GT1, bem como as poss\u00edveis medidas da PAC existentes para a promo\u00e7\u00e3o de artr\u00f3podes, ser\u00e3o testadas \u00e0 escala demonstrativa em diferentes territ\u00f3rios, culturas e tipos de sistemas de produ\u00e7\u00e3o, com o objetivo de obter uma metodologia robusta de promo\u00e7\u00e3o de artr\u00f3podes que possa ser replic\u00e1vel a outras [&hellip;]","og_url":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","article_modified_time":"2026-07-20T12:28:20+00:00","og_image":[{"width":344,"height":147,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\/","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\/","name":"Ensai-piloto das pr\u00e1ticas agroecol\u00f3gicas para a promo\u00e7\u00e3o de artr\u00f3podos - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#website"},"datePublished":"2026-07-20T12:28:16+00:00","dateModified":"2026-07-20T12:28:20+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/ensai-piloto-das-praticas-agroecologicas-para-a-promocao-de-artropodos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Ensai-piloto das pr\u00e1ticas agroecol\u00f3gicas para a promo\u00e7\u00e3o de artr\u00f3podos"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#website","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/piloto-proyecto-27\/50166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/piloto-proyecto-27"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/types\/piloto-proyecto-27"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/users\/6673"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=50166"}],"wp:term":[{"taxonomy":"convocatoria-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/convocatoria-proyecto-27?post=50166"},{"taxonomy":"estado-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/estado-proyecto-27?post=50166"},{"taxonomy":"objetivo-especifico-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/objetivo-especifico-proyecto-27?post=50166"},{"taxonomy":"pais-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/pais-proyecto-27?post=50166"},{"taxonomy":"periodo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/periodo?post=50166"},{"taxonomy":"prioridad-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/prioridad-proyecto-27?post=50166"},{"taxonomy":"publico-objetivo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/publico-objetivo?post=50166"},{"taxonomy":"region-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/region-proyecto-27?post=50166"},{"taxonomy":"tematica-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/tematica-proyecto-27?post=50166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}