{"id":50169,"date":"2026-07-20T13:55:22","date_gmt":"2026-07-20T11:55:22","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/?post_type=piloto-proyecto-27&#038;p=50169"},"modified":"2026-07-20T13:55:22","modified_gmt":"2026-07-20T11:55:22","slug":"acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial","status":"publish","type":"piloto-proyecto-27","link":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\/","title":{"rendered":"A\u00e7\u00e3o-piloto: Espacializar resultados das metodologias de parcelas, na decis\u00e3o de base territorial"},"content":{"rendered":"<p>O Douro \u00e9 a segunda maior bacia hidrogr\u00e1fica de Portugal e suporte de dois setores econ\u00f3micos estrat\u00e9gicos: o vinho e o turismo. Por ser uma  regi\u00e3o de viticultura de encosta, enfrenta problemas de disponibilidade e acessibilidade \u00e0 \u00e1gua, eros\u00e3o e perda de solo, colocando em causa o normal desenvolvimento (e sobreviv\u00eancia) das videiras. A viticultura \u00e9 dependente da disponibilidade de \u00e1gua e as altera\u00e7\u00f5es clim\u00e1ticas tornaram-na um recurso escasso, quer pelo aumento da temperatura, quer pela distribui\u00e7\u00e3o irregular da precipita\u00e7\u00e3o ao longo do ano, amea\u00e7ando a produ\u00e7\u00e3o de uvas de qualidade. Para fazer face \u00e0 escassez de \u00e1gua pode ser utilizada irriga\u00e7\u00e3o, contudo,  apesar da sua utilidade, a rega deve ser gerida cuidadosamente, para n\u00e3o comprometer os recursos h\u00eddricos e como complementaridade de outras estrat\u00e9gias de gest\u00e3o do stress h\u00eddrico. A tomada de decis\u00e3o na SYM \u00e9 feita com suporte dos dados do Sistema de Informa\u00e7\u00e3o Geogr\u00e1fica (SIG-Vinha), imagens de drone e de sat\u00e9lite, sondas de solo, sensores de fluxo de seiva e, ainda, medi\u00e7\u00f5es de potencial h\u00eddrico foliar. Embora eficazes, estes m\u00e9todos implicam custos elevados e consumo de tempo. A utiliza\u00e7\u00e3o de imagens de sat\u00e9lite \u00e9 uma oportunidade, pois permite aos viticultores acederem a informa\u00e7\u00e3o de forma f\u00e1cil e a baixo custo. Esta a\u00e7\u00e3o prop\u00f5e a realiza\u00e7\u00e3o de ensaios em parcelas piloto, onde os m\u00e9todos atualmente utilizados ser\u00e3o comparados com as tecnologias espaciais propostas pelo AgroSpace, com o objetivo de melhorar as metodologias de gest\u00e3o da \u00e1gua, baixa produtividade, entre outros. Os pilotos estar\u00e3o localizados em propriedades da SYM, no Douro, onde j\u00e1 existem ensaios de longa dura\u00e7\u00e3o e v\u00e1rios equipamentos instalados. Os resultados obtidos ser\u00e3o extrapolados das parcelas piloto para outras parcelas, utilizando as ferramentas geradas pelo Projeto. A dissemina\u00e7\u00e3o do conhecimento adquirido ser\u00e1 feito atrav\u00e9s de dias abertos \u00e0 comunidade, &#8216;Pilot Open Days&#8217;, dirigidos a t\u00e9cnicos do setor, com visitas \u00e0s parcelas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Douro \u00e9 a segunda maior bacia hidrogr\u00e1fica de Portugal e suporte de dois setores econ\u00f3micos estrat\u00e9gicos: o vinho e o turismo. Por ser uma regi\u00e3o de viticultura de encosta, enfrenta problemas de disponibilidade e acessibilidade \u00e0 \u00e1gua, eros\u00e3o e perda de solo, colocando em causa o normal desenvolvimento (e sobreviv\u00eancia) das videiras. A viticultura [&hellip;]<\/p>\n","protected":false},"author":6657,"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"convocatoria-proyecto-27":[3312],"estado-proyecto-27":[3364],"objetivo-especifico-proyecto-27":[4029,3914],"pais-proyecto-27":[],"periodo":[3557],"prioridad-proyecto-27":[3275,3912],"publico-objetivo":[],"region-proyecto-27":[],"tematica-proyecto-27":[],"class_list":["post-50169","piloto-proyecto-27","type-piloto-proyecto-27","status-publish","hentry","convocatoria-proyecto-27-2a-convocatoria-pt-pt","estado-proyecto-27-em-curso","objetivo-especifico-proyecto-27-1-1-desarrollar-y-mejorar-las-capacidades-de-investigacion-e-innovacion-y-asimilar-tecnologias-avanzadas-pt-pt","objetivo-especifico-proyecto-27-1-1-desenvolver-e-reforcar-as-capacidades-de-investigacao-e-inovacao-e-a-adocao-de-tecnologias-avancadas","periodo-2021-2027-pt-pt","prioridad-proyecto-27-2-promover-a-coesao-social-e-o-equilibrio-territorial-e-demografico-no-sudoe-atraves-da-inovacao-e-transformacao-dos-sectores-produtivos","prioridad-proyecto-27-2-promover-a-coesao-social-e-o-quilibrio-territorial-e-demografico-no-sudoe-atraves-da-inovacao-e-transformacao-dos-sectores-produtivos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A\u00e7\u00e3o-piloto: Espacializar resultados das metodologias de parcelas, na decis\u00e3o de base territorial - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A\u00e7\u00e3o-piloto: Espacializar resultados das metodologias de parcelas, na decis\u00e3o de base territorial - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"O Douro \u00e9 a segunda maior bacia hidrogr\u00e1fica de Portugal e suporte de dois setores econ\u00f3micos estrat\u00e9gicos: o vinho e o turismo. Por ser uma regi\u00e3o de viticultura de encosta, enfrenta problemas de disponibilidade e acessibilidade \u00e0 \u00e1gua, eros\u00e3o e perda de solo, colocando em causa o normal desenvolvimento (e sobreviv\u00eancia) das videiras. A viticultura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\\\/\",\"name\":\"A\u00e7\u00e3o-piloto: Espacializar resultados das metodologias de parcelas, na decis\u00e3o de base territorial - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#website\"},\"datePublished\":\"2026-07-20T11:55:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A\u00e7\u00e3o-piloto: Espacializar resultados das metodologias de parcelas, na decis\u00e3o de base territorial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A\u00e7\u00e3o-piloto: Espacializar resultados das metodologias de parcelas, na decis\u00e3o de base territorial - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\/","og_locale":"pt_PT","og_type":"article","og_title":"A\u00e7\u00e3o-piloto: Espacializar resultados das metodologias de parcelas, na decis\u00e3o de base territorial - Interreg Sudoe","og_description":"O Douro \u00e9 a segunda maior bacia hidrogr\u00e1fica de Portugal e suporte de dois setores econ\u00f3micos estrat\u00e9gicos: o vinho e o turismo. Por ser uma regi\u00e3o de viticultura de encosta, enfrenta problemas de disponibilidade e acessibilidade \u00e0 \u00e1gua, eros\u00e3o e perda de solo, colocando em causa o normal desenvolvimento (e sobreviv\u00eancia) das videiras. A viticultura [&hellip;]","og_url":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","og_image":[{"width":344,"height":147,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\/","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\/","name":"A\u00e7\u00e3o-piloto: Espacializar resultados das metodologias de parcelas, na decis\u00e3o de base territorial - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#website"},"datePublished":"2026-07-20T11:55:22+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/acao-piloto-espacializar-resultados-das-metodologias-de-parcelas-na-decisao-de-base-territorial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"A\u00e7\u00e3o-piloto: Espacializar resultados das metodologias de parcelas, na decis\u00e3o de base territorial"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#website","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/piloto-proyecto-27\/50169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/piloto-proyecto-27"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/types\/piloto-proyecto-27"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/users\/6657"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=50169"}],"wp:term":[{"taxonomy":"convocatoria-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/convocatoria-proyecto-27?post=50169"},{"taxonomy":"estado-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/estado-proyecto-27?post=50169"},{"taxonomy":"objetivo-especifico-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/objetivo-especifico-proyecto-27?post=50169"},{"taxonomy":"pais-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/pais-proyecto-27?post=50169"},{"taxonomy":"periodo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/periodo?post=50169"},{"taxonomy":"prioridad-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/prioridad-proyecto-27?post=50169"},{"taxonomy":"publico-objetivo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/publico-objetivo?post=50169"},{"taxonomy":"region-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/region-proyecto-27?post=50169"},{"taxonomy":"tematica-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/tematica-proyecto-27?post=50169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}