{"id":50176,"date":"2026-07-20T13:55:31","date_gmt":"2026-07-20T11:55:31","guid":{"rendered":"https:\/\/interreg-sudoe.eu\/?post_type=piloto-proyecto-27&#038;p=50176"},"modified":"2026-07-20T13:55:31","modified_gmt":"2026-07-20T11:55:31","slug":"piloto2-ecolab-2","status":"publish","type":"piloto-proyecto-27","link":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/piloto2-ecolab-2\/","title":{"rendered":"PILOTO2 ECOLAB"},"content":{"rendered":"<p>Neste caso, ser\u00e1 realizada uma colabora\u00e7\u00e3o transfronteiri\u00e7a entre adegas e centros de investiga\u00e7\u00e3o da FR, ES e PT, combinando as suas especialidades para obter um melhor aproveitamento dos RLC gerados no setor vitivin\u00edcola. Todas as adegas do espa\u00e7o SUDOE devem enfrentar o desafio de melhorar a sua competitividade num mercado global e a resili\u00eancia a crises. A partir do PILOTO2 ECOLAB procura-se abordar esse problema sob dois pontos de vista: a) Obten\u00e7\u00e3o de uma pequena quantidade de produtos do RLC, que possuem um valor elevado; b) Obten\u00e7\u00e3o de um grande n\u00famero de produtos a partir dos RLC, mas de menor valor. Al\u00e9m disso, pretende-se utilizar v\u00e1rios tipos de m\u00e9todos de processamento, otimizados para maximizar a produ\u00e7\u00e3o de componentes valiosos, minimizando os fluxos de res\u00edduos e convertendo a quantidade necess\u00e1ria de componentes de menor valor em fertilizantes energ\u00e9ticos ou ecol\u00f3gicos. Nesse caso, as a\u00e7\u00f5es incluir\u00e3o: 1. Estimar o potencial que os diferentes tipos de RLC vitivin\u00edcolas possuem, tanto para o desenvolvimento de produtos renov\u00e1veis inovadores e diferenci\u00e1veis, como para a produ\u00e7\u00e3o de energia (biog\u00e1s). As informa\u00e7\u00f5es recolhidas estabelecer\u00e3o as bases para no futuro dimensionar otros sistemas. 2. Estabelecer os melhores m\u00e9todos\/condi\u00e7\u00f5es para realizar a separa\u00e7\u00e3o\/fracionamento dos compostos de interesse destes RLC vitivin\u00edcolas. 3. Desenvolver formula\u00e7\u00f5es e bioprodutos a partir das diferentes fra\u00e7\u00f5es de RLC, especialmente para aplica\u00e7\u00f5es farmac\u00eauticas e alimentares (ex. nanopart\u00edculas de lignina, filmes ativos e hidrog\u00e9is com atividade anti-inflamat\u00f3ria e\/ou antibacteriana, biotintas). Com estas a\u00e7\u00f5es, ser\u00e1 promovida a utiliza\u00e7\u00e3o dos recursos dispon\u00edveis, promovendo a ecoefici\u00eancia no \u00e2mbito de uma econom\u00eda circular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste caso, ser\u00e1 realizada uma colabora\u00e7\u00e3o transfronteiri\u00e7a entre adegas e centros de investiga\u00e7\u00e3o da FR, ES e PT, combinando as suas especialidades para obter um melhor aproveitamento dos RLC gerados no setor vitivin\u00edcola. Todas as adegas do espa\u00e7o SUDOE devem enfrentar o desafio de melhorar a sua competitividade num mercado global e a resili\u00eancia a [&hellip;]<\/p>\n","protected":false},"author":6691,"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_monsterinsights_skip_tracking":false,"_members_access_role":[],"_members_access_error":""},"convocatoria-proyecto-27":[3312],"estado-proyecto-27":[3364],"objetivo-especifico-proyecto-27":[4029,3914],"pais-proyecto-27":[],"periodo":[3557],"prioridad-proyecto-27":[3275,3912],"publico-objetivo":[],"region-proyecto-27":[],"tematica-proyecto-27":[],"class_list":["post-50176","piloto-proyecto-27","type-piloto-proyecto-27","status-publish","hentry","convocatoria-proyecto-27-2a-convocatoria-pt-pt","estado-proyecto-27-em-curso","objetivo-especifico-proyecto-27-1-1-desarrollar-y-mejorar-las-capacidades-de-investigacion-e-innovacion-y-asimilar-tecnologias-avanzadas-pt-pt","objetivo-especifico-proyecto-27-1-1-desenvolver-e-reforcar-as-capacidades-de-investigacao-e-inovacao-e-a-adocao-de-tecnologias-avancadas","periodo-2021-2027-pt-pt","prioridad-proyecto-27-2-promover-a-coesao-social-e-o-equilibrio-territorial-e-demografico-no-sudoe-atraves-da-inovacao-e-transformacao-dos-sectores-produtivos","prioridad-proyecto-27-2-promover-a-coesao-social-e-o-quilibrio-territorial-e-demografico-no-sudoe-atraves-da-inovacao-e-transformacao-dos-sectores-produtivos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PILOTO2 ECOLAB - Interreg Sudoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/piloto2-ecolab-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PILOTO2 ECOLAB - Interreg Sudoe\" \/>\n<meta property=\"og:description\" content=\"Neste caso, ser\u00e1 realizada uma colabora\u00e7\u00e3o transfronteiri\u00e7a entre adegas e centros de investiga\u00e7\u00e3o da FR, ES e PT, combinando as suas especialidades para obter um melhor aproveitamento dos RLC gerados no setor vitivin\u00edcola. Todas as adegas do espa\u00e7o SUDOE devem enfrentar o desafio de melhorar a sua competitividade num mercado global e a resili\u00eancia a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/piloto2-ecolab-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Interreg Sudoe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/interregsudoe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Sudoe5\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/piloto2-ecolab-2\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/piloto2-ecolab-2\\\/\",\"name\":\"PILOTO2 ECOLAB - Interreg Sudoe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#website\"},\"datePublished\":\"2026-07-20T11:55:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/piloto2-ecolab-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/piloto2-ecolab-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/piloto-proyecto-27\\\/piloto2-ecolab-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PILOTO2 ECOLAB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\",\"name\":\"Interreg Sudoe\",\"description\":\"Interreg Sudoe\",\"publisher\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#organization\"},\"alternateName\":\"Interreg Sudoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#organization\",\"name\":\"Interreg Sudoe\",\"alternateName\":\"Interreg Sudoe\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"contentUrl\":\"https:\\\/\\\/interreg-sudoe.eu\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/logo-interreg.png\",\"width\":1200,\"height\":675,\"caption\":\"Interreg Sudoe\"},\"image\":{\"@id\":\"https:\\\/\\\/interreg-sudoe.eu\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/interregsudoe\",\"https:\\\/\\\/x.com\\\/Sudoe5\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGx2edoB32beRc9dbKA2vw\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/interreg-sudoe-programme\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/148704685@N06\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PILOTO2 ECOLAB - Interreg Sudoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/piloto2-ecolab-2\/","og_locale":"pt_PT","og_type":"article","og_title":"PILOTO2 ECOLAB - Interreg Sudoe","og_description":"Neste caso, ser\u00e1 realizada uma colabora\u00e7\u00e3o transfronteiri\u00e7a entre adegas e centros de investiga\u00e7\u00e3o da FR, ES e PT, combinando as suas especialidades para obter um melhor aproveitamento dos RLC gerados no setor vitivin\u00edcola. Todas as adegas do espa\u00e7o SUDOE devem enfrentar o desafio de melhorar a sua competitividade num mercado global e a resili\u00eancia a [&hellip;]","og_url":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/piloto2-ecolab-2\/","og_site_name":"Interreg Sudoe","article_publisher":"https:\/\/www.facebook.com\/interregsudoe","og_image":[{"width":344,"height":147,"url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/download.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Sudoe5","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/piloto2-ecolab-2\/","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/piloto2-ecolab-2\/","name":"PILOTO2 ECOLAB - Interreg Sudoe","isPartOf":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#website"},"datePublished":"2026-07-20T11:55:31+00:00","breadcrumb":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/piloto2-ecolab-2\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/piloto2-ecolab-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/piloto-proyecto-27\/piloto2-ecolab-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/interreg-sudoe.eu\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"PILOTO2 ECOLAB"}]},{"@type":"WebSite","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#website","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/","name":"Interreg Sudoe","description":"Interreg Sudoe","publisher":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#organization"},"alternateName":"Interreg Sudoe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/interreg-sudoe.eu\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#organization","name":"Interreg Sudoe","alternateName":"Interreg Sudoe","url":"https:\/\/interreg-sudoe.eu\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","contentUrl":"https:\/\/interreg-sudoe.eu\/wp-content\/uploads\/2024\/03\/logo-interreg.png","width":1200,"height":675,"caption":"Interreg Sudoe"},"image":{"@id":"https:\/\/interreg-sudoe.eu\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/interregsudoe","https:\/\/x.com\/Sudoe5","https:\/\/www.youtube.com\/channel\/UCeGx2edoB32beRc9dbKA2vw","https:\/\/www.linkedin.com\/company\/interreg-sudoe-programme\/","https:\/\/www.flickr.com\/photos\/148704685@N06\/"]}]}},"_links":{"self":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/piloto-proyecto-27\/50176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/piloto-proyecto-27"}],"about":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/types\/piloto-proyecto-27"}],"author":[{"embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/users\/6691"}],"wp:attachment":[{"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/media?parent=50176"}],"wp:term":[{"taxonomy":"convocatoria-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/convocatoria-proyecto-27?post=50176"},{"taxonomy":"estado-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/estado-proyecto-27?post=50176"},{"taxonomy":"objetivo-especifico-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/objetivo-especifico-proyecto-27?post=50176"},{"taxonomy":"pais-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/pais-proyecto-27?post=50176"},{"taxonomy":"periodo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/periodo?post=50176"},{"taxonomy":"prioridad-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/prioridad-proyecto-27?post=50176"},{"taxonomy":"publico-objetivo","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/publico-objetivo?post=50176"},{"taxonomy":"region-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/region-proyecto-27?post=50176"},{"taxonomy":"tematica-proyecto-27","embeddable":true,"href":"https:\/\/interreg-sudoe.eu\/pt-pt\/wp-json\/wp\/v2\/tematica-proyecto-27?post=50176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}